{"id":6054,"date":"2014-03-31T20:07:05","date_gmt":"2014-03-31T20:07:05","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=6054"},"modified":"2014-03-31T20:07:05","modified_gmt":"2014-03-31T20:07:05","slug":"if-muriae-realiza-palestra-e-debate-sobre-os-50-anos-de-golpe-civico-e-militar","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/6054","title":{"rendered":"IF- Muria\u00e9 realiza palestra e debate sobre os 50 anos de Golpe C\u00edvico e Militar"},"content":{"rendered":"\n<p>No dia 28 de Mar\u00e7o, ocorreu no Campus Muria\u00e9 do IFSEMG uma palestra, organizado pelo N\u00facleo de Ci\u00eancias Humanas, sobre os 50 anos do Golpe Militar. O evento contou com a presen\u00e7a do Sr. Jos\u00e9 Francisco N\u00e9res, oper\u00e1rio tecel\u00e3o, sindicalista, vereador comunista, cassado em 1964 e \u00faltimo preso pol\u00edtico do per\u00edodo da ditadura militar.<\/p>\n<p>Sob a coordena\u00e7\u00e3o dos professores F\u00e1bio Peixoto (sociologia), Sirleia Arantes (Hist\u00f3ria), F\u00e1bio Bezerra (Filosofia) e J\u00falio Monerat (Geografia) o evento ocorreu nos tr\u00eas turnos, pela manh\u00e3 \u00a0e a noite na unidade da Barra e a tarde na unidade rural, contando com a participa\u00e7\u00e3o aproximada de mais de 350 pessoas entre a comunidade do IFET e estudantes de outras faculdades.<\/p>\n<p>Neres falou sobre os acontecimentos antes do golpe c\u00edvico-militar, sobre a resist\u00eancia do movimento popular, a luta pela democracia, a pris\u00e3o no DOPS, a tortura, a redemocratiza\u00e7\u00e3o e a participa\u00e7\u00e3o, os limites e os avan\u00e7os da Comiss\u00e3o da Verdade, do qual faz parte.<\/p>\n<p>Em um depoimento emocionado e rico em informa\u00e7\u00f5es, os professores do N\u00facleo de Ci\u00eancias Humanas, aproveitaram o ensejo para contextualizar o per\u00edodo de 21 anos de Ditadura, enriquecendo a palestra com um prof\u00edcuo debate envolvendo quest\u00f5es da \u00e9poca e da atualidade pol\u00edtica e social brasileira, possibilitando aos alunos e servidores presentes uma importante e necess\u00e1ria reflex\u00e3o sobre um per\u00edodo que marcou a hist\u00f3ria e as gera\u00e7\u00f5es precedentes at\u00e9 nossos dias.<\/p>\n<p> <object class=\"imagem100\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/ddCZW82mRlM\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><\/object> <\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=ddCZW82mRlM\" target=\"_blank\">https:\/\/www.youtube.com\/watch?v=ddCZW82mRlM<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/6054\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-6054","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1zE","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=6054"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6054\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=6054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=6054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=6054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}