{"id":6126,"date":"2014-04-15T04:26:09","date_gmt":"2014-04-15T04:26:09","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=6126"},"modified":"2016-06-05T16:55:33","modified_gmt":"2016-06-05T19:55:33","slug":"solidariedade-militante-a-ocupacao-amarildo","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/6126","title":{"rendered":"N\u00e3o encostem em Amarildo!"},"content":{"rendered":"<p>Na tarde de s\u00e1bado, 12 de abril de 2014, mais um ocorrido na Ilha de Santa Catarina nos chama a aten\u00e7\u00e3o com tristeza e revolta, mal passados 15 dias da truculenta e absurda a\u00e7\u00e3o da Pol\u00edcia Federal e Militar no Campus da Universidade Federal de Santa Catariana e tamb\u00e9m recentes a\u00e7\u00f5es de repressoras da PM nas ocupa\u00e7\u00f5es Palmares e Contestado, nos fazem refletir e perceber com clareza o Estado mostrando para que existe e mant\u00e9m a for\u00e7a policial, e em particular a PM, <!--more-->que por meio de sua tropa de choque, age, com o uso legitimo da for\u00e7a, para defender a propriedade privada da terra e atacar os movimentos sociais, agindo nestes termos at\u00e9 mesmo para um peda\u00e7o de terra que fora grilado e pelo movimento provado ser p\u00fablica, mas que, localizada ao norte nobre da Ilha n\u00e3o pode ser utilizada como moradia para a classe trabalhadora. Registramos aqui e em nossas a\u00e7\u00f5es o rep\u00fadio ao Estado Burocr\u00e1tico Burgu\u00eas que se utiliza de tais expedientes militares para reprimir e exterminar a classe trabalhadora, a juventude pobre, negra e criminalizar qualquer a\u00e7\u00e3o de movimentos sociais que lutem por condi\u00e7\u00f5es de vida.<\/p>\n<p>Manifestamos nossa solidariedade militante \u00e0 luta pela terra, trabalho e teto travada bravamente pelos n\u00facleos da Ocupa\u00e7\u00e3o Amarildo, que com organiza\u00e7\u00e3o e muito trabalho produziram e resistiram na terra, em seus barracos, suas cozinhas coletivas, vivendo, construindo e possibilitando um outro e novo mundo poss\u00edvel.<\/p>\n<p>A luta n\u00e3o para, dela n\u00e3o sairemos, continuaremos na luta pela reforma agr\u00e1ria e popular e e pelo direito a cidade. A mudan\u00e7a, agora, nos soa como um grito de vit\u00f3ria, por tudo conquistado nestes meses de ocupa\u00e7\u00e3o as viv\u00eancias, as alegrias das crian\u00e7as a consci\u00eancia coletiva e transformadora gerada pelo exerc\u00edcio do Poder Popular.<\/p>\n<p>Chamamos a todas e todos para que desde hoje dia 14 de abril estejamos em vig\u00edlia, a pressionar o Governo do Estado para encaminhar a melhor decis\u00e3o para estas fam\u00edlias de lutadoras e lutadores conscientes de suas condi\u00e7\u00f5es e necessidades. Atentos para o dia 15 de abril, nos mantermos na press\u00e3o para que o Estado indique para este novo momento do movimento, uma solu\u00e7\u00e3o segura que caminhar\u00e1 para a conquista da terra, para l\u00e1 continuar a lutar, resistir e produzir.<\/p>\n<p>Por terra trabalho e teto!<\/p>\n<p>Reforma agr\u00e1ria e urbana j\u00e1!<\/p>\n<p>Pelo Poder Popular!<\/p>\n<p>Partido Comunista Brasileiro<\/p>\n<p>Comit\u00ea Regional de Santa Catarina<\/p>\n<p><a href=\"http:\/\/pcbsc.wordpress.com\/2014\/04\/15\/nao-encostem-em-amarildo\/\">N\u00e3o encostem em&nbsp;Amarildo!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/6126\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-6126","post","type-post","status-publish","format-standard","hentry","category-c25-notas-politicas-do-pcb"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1AO","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=6126"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6126\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=6126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=6126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=6126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}