{"id":6131,"date":"2014-04-16T14:15:30","date_gmt":"2014-04-16T14:15:30","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=6131"},"modified":"2014-04-16T14:15:30","modified_gmt":"2014-04-16T14:15:30","slug":"prefeitura-tenta-enganar-mas-sem-teto-nao-arredam-pe-vamos-ficar-aqui-ate-ter-resposta-o-povo-quer-casa","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/6131","title":{"rendered":"Prefeitura tenta enganar, mas Sem Teto n\u00e3o arredam p\u00e9: \u201cVamos ficar aqui at\u00e9 ter resposta. O povo quer casa!\u201d"},"content":{"rendered":"\n<p><em><strong>Funcion\u00e1rios da prefeitura oferecem como proposta um cadastro como este da foto. Nele, o declarante \u00e9 obrigado a dizer que ocupou o \u201cpr\u00e9dio da empresa de telefonia Oi\u201d, e recebe uma garantia vaga de algum dia, receber uma moradia. O relato do atendimento chega a ser c\u00f4mico.<\/strong><\/em><\/p>\n<p><em>do Boletim do MST-RJ<\/em><\/p>\n<p>&#8211; Onde voc\u00ea mora?<\/p>\n<p>&#8211; N\u00e3o tenho casa, senhora.<\/p>\n<p>&#8211; Quanto a senhora paga de aluguel?<\/p>\n<p>&#8211; N\u00e3o tenho casa, senhora.<\/p>\n<p>&#8211; Quantas pessoas moram na sua casa?<\/p>\n<p>&#8211; Senhora, eu j\u00e1 disse que eu n\u00e3o tenho casa.<\/p>\n<p>Ap\u00f3s o cadastro:<\/p>\n<p>&#8211; A senhora j\u00e1 pode voltar para casa, e n\u00f3s entraremos em contato.<\/p>\n<p>&#8211; Senhora, qual parte do \u201ceu n\u00e3o tenho casa\u201d voc\u00ea n\u00e3o entendeu? E como a senhora vai entrar em contato comigo se n\u00e3o pegou meu telefone?<\/p>\n<p>* * *<\/p>\n<p><img data-recalc-dims=\"1\" height=\"682\" width=\"512\" decoding=\"async\" class=\"imagem\" src=\"https:\/\/i0.wp.com\/boletimmstrj.mst.org.br\/img\/IMG_0548-512x682.jpg?resize=512%2C682\" border=\"0\" \/>* * *<\/p>\n<p>Ontem \u00e0 noite, os Sem Teto n\u00e3o puderam dormir. Os carros de pol\u00edcia ligavam a sirene toda hora. As crian\u00e7as n\u00e3o tinham como dormir, ainda em frente \u00e0 prefeitura. Nessa hora eles j\u00e1 haviam sido expulsos da passarela pelo choque. Eles disseram: \u201cou voc\u00eas descem ou v\u00e3o descer rolando\u201d.<\/p>\n<p>Os advogados foram conversar com o comandante, que disse que iria acordar todo mundo \u00e0s 5:00h. E foi isso que eles fizeram. E deram 10 minutos que as pessoas sa\u00edssem da frente da prefeitura. Ou saiam, ou iam receber do choque e da GM o tratamento que a gente j\u00e1 conhece.<\/p>\n<p>As pessoas ent\u00e3o foram para debaixo da marquise antes da prefeitura, entre os Bancos Bradesco e\u00a0do Brasil, que nem abriu hoje, porque ficaram com medo. O n\u00famero de doa\u00e7\u00f5es hoje foi bem abaixo do necess\u00e1rio. Mais cedo um garoto foi atropelado, voou longe, quebrou a mand\u00edbula, a clav\u00edcula, e tinha po\u00e7a de sangue enorme. Os guardas tentaram estancar o sangue mas era imposs\u00edvel. Os bombeiros chegaram r\u00e1pido, mas ele foi pro Souza Aguiar e faleceu. O nome dele \u00e9 Fernando, e ele era de Manguinhos.<\/p>\n<p>A prefeitura marcou uma reuni\u00e3o em Bonsucesso, sendo que a Secretaria de Habita\u00e7\u00e3o \u00e9 na Cidade Nova. A reuni\u00e3o n\u00e3o teve resultado, e os moradores que j\u00e1 estavam revoltados e com fome, desde de manh\u00e3. Um garoto foi preso, morador de Manguinhos, por roubar balas de uma loja.<\/p>\n<p>Se o delegado fosse razo\u00e1vel, j\u00e1 teria soltado ele. Mas ele est\u00e1 levando em considera\u00e7\u00e3o as quest\u00f5es pol\u00edticas. Um advogado entrou e foi falar com o menino, e falou que ele tinha o direito de permanecer em sil\u00eancio. E a\u00ed o delegado falou: \u201cAdvogado n\u00e3o fala dentro da minha delegacia.\u201d Tipificou como roubo qualificado, e disse para o advogado que era uma quest\u00e3o pessoal, ou seja, o delegado est\u00e1 descontando no garoto de 20 anos uma quest\u00e3o dele com o advogado.<\/p>\n<p>* * *<\/p>\n<p><img data-recalc-dims=\"1\" height=\"384\" width=\"512\" decoding=\"async\" class=\"imagem\" src=\"https:\/\/i0.wp.com\/boletimmstrj.mst.org.br\/img\/IMG_0542-512x384.jpg?resize=512%2C384\" border=\"0\" \/><\/p>\n<p>* * *<\/p>\n<p>&#8211; O que voc\u00eas v\u00e3o fazer agora?<\/p>\n<p>&#8211; Vamos ficar aqui esperando uma resposta n\u00e9? Porque por enquanto, essa aqui t\u00e1 sendo nossa moradia. Isso \u00e9 o que a prefeitura nos proporciona.\u00a0Isso \u00e9 o que a prefeitura proporciona pra popula\u00e7\u00e3o brasileira.<\/p>\n<p>&#8211; Porque voc\u00eas acham que isso t\u00e1 acontecendo?<\/p>\n<p>&#8211; \u00c9 o descaso das autoridades. Descaso, descaso. Eles n\u00e3o querem dar nada pra gente. N\u00e3o quer pagar, n\u00e3o quer dar uma moradia pra gente, digna, porque n\u00f3s merece. Educa\u00e7\u00e3o, sa\u00fade, uma moradia, o direito que o pobre, eles n\u00e3o t\u00e3o dando esse direito pra gente. S\u00f3 querem dar porrada na gente. As autoridades que vem pro nosso pa\u00eds pensam que o Brasil \u00e9 feito de futebol, de Copa, de carnaval, de festa, entendeu, de Maracan\u00e3\u2026 Mas a verdadeira popula\u00e7\u00e3o somos n\u00f3s, n\u00f3s que pagamos os maiores impostos. Porque o rico sonega. T\u00e1 entendendo? Mas eles n\u00e3o veem isso, entendeu? Pra eles n\u00f3s somos apenas a minoria. Mas eles est\u00e3o enganados. Porque o povo vai resistir. O povo n\u00e3o tem pra onde ir mesmo. At\u00e9 porque n\u00f3s nem t\u00ednhamos pra onde ir, e abrigo n\u00f3s n\u00e3o vamos aceitar. N\u00f3s mor\u00e1vamos num barraco l\u00e1, que era madeira, era ruim, mas era nosso. Entendeu? Tiraram assim, de uma forma sem nenhuma estrutura, sem negociar nada.<\/p>\n<p>&#8211; Voc\u00ea estava l\u00e1 no dia?<\/p>\n<p>&#8211; Eu estava l\u00e1 no dia da invas\u00e3o. Foi horr\u00edvel, foi horr\u00edvel, foi horr\u00edvel\u2026 A minha comadre deram tr\u00eas cacetadas na perna dela, porque ela voltou pra pegar a filha, entendeu? Jogaram ela da escada, foi horr\u00edvel, foi horr\u00edvel. Comigo gra\u00e7as a Deus, o que me atingiu muito foi spray de pimenta e o g\u00e1s n\u00e9, mas espancamento n\u00e3o. Mas eu v\u00ed muitas pessoas sendo espancadas, mal tratadas, jornalistas. Pegaram as pessoas que estava querendo mostrar o que estava acontecendo com a gente, eu assisti tamb\u00e9m, jornalista tendo seus materiais e seus equipamentos quebrados. pisoteados, porque queriam mostrar a realidade do Brasil, que eles querem esconder.<\/p>\n<p>&#8211; Voc\u00eas v\u00e3o ficar aqui at\u00e9 quando?<\/p>\n<p>&#8211; At\u00e9 eles resolverem nossa casa. Me dar uma moradia. Que eu n\u00e3o tenho onde ficar, meu filho t\u00e1 na casa da minha sogra, eu n\u00e3o posso morar em de sogra, eu n\u00e3o tenho casa. To nessa situa\u00e7\u00e3o aqui, eu e minha mulher. Vamos ficar aqui at\u00e9 ter resposta. O povo n\u00e3o vai desistir. O povo quer casa!<\/p>\n<p>* * *<\/p>\n<p><img data-recalc-dims=\"1\" height=\"384\" width=\"512\" decoding=\"async\" class=\"imagem\" src=\"https:\/\/i0.wp.com\/boletimmstrj.mst.org.br\/img\/IMG_0546-512x384.jpg?resize=512%2C384\" border=\"0\" alt=\"IMG_0546\" \/><\/p>\n<p>* * *<\/p>\n<p>&#8211; A frase que eu mais escutei aqui foi \u201cTiro, porrada e bomba.\u201d<\/p>\n<p>&#8211; Minha filha quase morreu queimada. A gente morava no segundo andar, tava tudo escuro, eu n\u00e3o enxerguei eles, vierem no corredor \u2013 HU-HU-HU, e eu, que isso? Quando olhei s\u00f3 vejo fogo, me arranhei todinha, gra\u00e7as a Deus minha filha n\u00e3o se machucou. Minha filha com um ano. Morando dentro do barraco, eles chegaram tacando fogo, batendo nos outros.<\/p>\n<p>&#8211; Eles tacaram fogo com voc\u00eas dentro do barraco?<\/p>\n<p>&#8211; Com todo mundo, derrubaram os barracos com morador dormindo debaixo, \u00e9 mentira? Claro que n\u00e3o. Eles derrubaram os barracos com todo mundo dormindo embaixo. Eles foram l\u00e1 agredir n\u00f3s sem n\u00f3s convidar eles. Ainda pediram caf\u00e9 da manh\u00e3. Pegaram minhas mercadorias todas que n\u00f3s tinha l\u00e1 pra montar o barraquinho, pra ganhar o p\u00e3o de cada dia. E tudo que sobrou, eles comeram e beberam. Tudo que sobrou da minha t\u00e1 aqui comigo \u00f3 (mostra um colchonete e uma mochila).<\/p>\n<p>&#8211; Da minha n\u00e3o sobrou nada. Foi tudo queimado. S\u00f3 a \u00fanica coisa que sobrou (tira uma identidade de dentro da blusa) foi meu documento, mesmo assim porque estava comigo.<\/p>\n<p>&#8211; Por que \u00e9 que voc\u00eas foram para a ocupa\u00e7\u00e3o?<\/p>\n<p>&#8211; Porque a gente n\u00e3o tem onde ficar. N\u00f3s n\u00e3o temos onde ficar. Se a gente tivesse onde ficar n\u00e3o tava dormindo aqui na rua. Se n\u00f3s tiv\u00e9ssemos pelo menos um emprego decente, um emprego digno, que pagasse um sal\u00e1rio decente pra n\u00f3s podermos pagar um aluguel, entendeu, mas eu acho que o Brasil \u00e9 um pa\u00eds muito rico, n\u00e3o tem necessidade de ningu\u00e9m viver de aluguel.<\/p>\n<p>&#8211; Quanto \u00e9 um aluguel onde voc\u00ea morava?<\/p>\n<p>&#8211; Ah, um aluguel de uma quitinete l\u00e1 t\u00e1 por volta de R$350. E pra quem ganha um sal\u00e1rio como a gente tem, como n\u00f3s vamos pagar aluguel, material escolar pro filho, alimento pra dentro de casa, luz, \u00e9 muita coisa, \u00e9 muita coisa e pouca op\u00e7\u00e3o. N\u00f3s n\u00e3o temos op\u00e7\u00f5es. O Brasil t\u00e1 criando marginais, cara. O Brasil t\u00e1 criando marginais. Olha o que eles est\u00e3o fazendo com a popula\u00e7\u00e3o.<\/p>\n<blockquote data-secret=\"Vch2iZ1Ulk\" class=\"wp-embedded-content\"><p><a href=\"http:\/\/boletimmstrj.mst.org.br\/prefeitura-tenta-enganar-mas-sem-teto-nao-arredam-pe-vamos-ficar-aqui-ate-ter-resposta-o-povo-nao-vai-desistir-o-povo-quer-casa\/\">Prefeitura tenta enganar, mas Sem Teto n\u00e3o arredam p\u00e9: &#8220;Vamos ficar aqui at\u00e9 ter resposta. O povo quer casa!&#8221;<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/boletimmstrj.mst.org.br\/prefeitura-tenta-enganar-mas-sem-teto-nao-arredam-pe-vamos-ficar-aqui-ate-ter-resposta-o-povo-nao-vai-desistir-o-povo-quer-casa\/embed\/#?secret=Vch2iZ1Ulk\" data-secret=\"Vch2iZ1Ulk\" width=\"600\" height=\"338\" title=\"&#8220;Prefeitura tenta enganar, mas Sem Teto n\u00e3o arredam p\u00e9: &#8220;Vamos ficar aqui at\u00e9 ter resposta. O povo quer casa!&#8221;&#8221; &#8212; Boletim do MST Rio\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/6131\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[],"class_list":["post-6131","post","type-post","status-publish","format-standard","hentry","category-c1-popular"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1AT","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=6131"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6131\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=6131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=6131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=6131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}