{"id":6524,"date":"2014-07-28T19:46:37","date_gmt":"2014-07-28T19:46:37","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=6524"},"modified":"2014-07-28T19:46:37","modified_gmt":"2014-07-28T19:46:37","slug":"camarada-do-pcb-em-goias-clovis-bueno-aos-107-anos-recebe-a-medalha-dinarco-reis","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/6524","title":{"rendered":"Camarada do PCB em Goi\u00e1s, Cl\u00f3vis Bueno, aos 107 anos, recebe a Medalha Dinarco Reis"},"content":{"rendered":"\n<p>Na semana passada, com a presen\u00e7a do Presidente da Funda\u00e7\u00e3o Dinarco Reis (Dinarco Reis Filho), do Secret\u00e1rio Geral do PCB (Ivan Pinheiro), da Secret\u00e1ria Pol\u00edtica do PCB em Goi\u00e1s (Marta Jane) e de v\u00e1rios militantes do Partido no Estado, o camarada Cl\u00f3vis Bueno, que far\u00e1 107 anos em novembro deste ano, recebeu a Medalha Dinarco Reis, em concorrida e emocionante cerim\u00f4nia em An\u00e1polis (GO), no Col\u00e9gio Galileu.<\/p>\n<p>O ato contou com a presen\u00e7a da esposa, filhos, parentes, amigos e companheiros de Cl\u00f3vis Bueno e intelectuais da cidade de An\u00e1polis, que discorreram sobre as lutas populares e a presen\u00e7a dos comunistas na hist\u00f3ria da cidade e regi\u00e3o. Usaram da palavra os representantes do PCB e da Funda\u00e7\u00e3o Dinarco Reis, um dirigente do PSOL, os filhos de Cl\u00f3vis Bueno e camaradas contempor\u00e2neos de lutas do homenageado.<\/p>\n<p>Dinarco Reis Filho resumiu a hist\u00f3ria ainda viva de Cl\u00f3vis Bueno, no momento que antecedeu a entrega da Medalha que leva o nome de seu pai, Dinarco Reis, que foi um membro do Comit\u00ea Central do Partido que marcou sua milit\u00e2ncia pela coragem revolucion\u00e1ria e pelo esp\u00edrito internacionalista. Assim foi resumida a vida do camarada Cl\u00f3vis Bueno:<\/p>\n<p><em>\u201cCl\u00f3vis Bueno far\u00e1 107 anos em 2014, j\u00e1 que nasceu no dia 30 de novembro de 1907, na cidade da Maranguape, Estado do Cear\u00e1. Foi para o Rio de Janeiro onde se formou em agrimensura e por l\u00e1 entrou no PCB (Partido Comunista Brasileiro). Teve contato com Luiz Carlos Prestes e conviveu mais de perto com Carlos Marighela. Participou do levante popular de 1935 que pretendia derrubar Get\u00falio Vargas do poder, movimento que ficou conhecido como Insurrei\u00e7\u00e3o Comunista de 1935. Por conta disso, foi preso por tr\u00eas anos e depois resolveu ir para S\u00e3o Paulo, onde trabalhou em um escrit\u00f3rio de advocacia. Com as persegui\u00e7\u00f5es ainda no Estado Novo (1937-1945), resolveu se interiorizar. Vai para Campinas, depois Tri\u00e2ngulo Mineiro e por fim chega a Goi\u00e1s no in\u00edcio da d\u00e9cada quarenta. Em Corumba\u00edba conhece Abiss\u00ednia e j\u00e1 s\u00e3o 61 anos de casamento, com tr\u00eas filhos, dois morando em S\u00e3o Paulo e um em Bras\u00edlia. Tem apenas um neto, sobre isso os dois brincam dizendo que os filhos n\u00e3o foram muito produtivos. O primog\u00eanito recebeu o nome de Lenine, uma homenagem ao l\u00edder da Revolu\u00e7\u00e3o Russa de 1917. Em 1945 migra para Pires do Rio, onde funda o PCB. Participou das lutas hist\u00f3ricas do Partido como a Campanha do Petr\u00f3leo em 1953, da resist\u00eancia ao regime militar, entre as d\u00e9cadas de sessenta e oitenta e da campanha pela abertura pol\u00edtica na d\u00e9cada de oitenta. Ap\u00f3s o fim do regime militar, Cl\u00f3vis se reintegra ao PCB no ano de 1985. Ainda hoje participa das discuss\u00f5es pol\u00edticas tanto na cidade, quanto no Brasil. Desde 1948 mora em An\u00e1polis com Abiss\u00ednia Bueno Monteiro, que, sempre com bom humor, lembra os fatos que tamb\u00e9m viveu com seu companheiro de vida.\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/6524\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-6524","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1He","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=6524"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6524\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=6524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=6524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=6524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}