{"id":6628,"date":"2014-08-24T04:43:58","date_gmt":"2014-08-24T04:43:58","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=6628"},"modified":"2014-08-24T04:43:58","modified_gmt":"2014-08-24T04:43:58","slug":"os-lsalvadoresr-do-iraque-e-la-arte-da-guerrar","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/6628","title":{"rendered":"Os \u00absalvadores\u00bb do Iraque e \u00abA arte da guerra\u00bb"},"content":{"rendered":"\n<p>Situando a atual operac\u0327a\u0303o jihadista no Iraque a longo prazo, o geo\u0301grafo Manlio Dinucci na\u0303o a interpreta como um transbordamento da guerra na Si\u0301ria, mas como a terceira guerra dos EUA no Iraque. Por conseque\u0302ncia, para ele, e\u0301 a guerra na Si\u0301ria, que e\u0301 um transbordo da guerra no Iraque.<\/p>\n<p>Os primeiros cac\u0327a-bombardeiros norte-americanos, que no Iraque atacaram, a 8 de agosto, objectivos na zona controlada pelo Emirado Isla\u0302mico, descolaram (decolaram- Br) do porta-avio\u0303es batizado George HW Bush, em homenagem do presidente republicano, autor em 1991 da primeira guerra contra o Iraque. Copiado pelo seu filho, George W. Bush, que em 2003 atacou e ocupou o pai\u0301s, acusando para isso Saddam Hussein (com base em \u00abprovas\u00bb que mais tarde se revelaram falsificadas) de possuir armas de destruic\u0327a\u0303o em massa e apoiar al-Qaida. Depois de ter empregue na guerra interna no Iraque mais de um milha\u0303o de soldados, ale\u0301m de centenas de milhares de aliados e mercena\u0301rios, os Estados Unidos sai\u0301ram substancialmente derrotados, sem chegar a conseguir realizar o objectivo de controlo total deste pai\u0301s, com importa\u0302ncia primordial pela sua posic\u0327a\u0303o estrate\u0301gica no Pro\u0301ximo-Oriente e pelas suas reservas petroli\u0301feras.<\/p>\n<p>E\u0301 aqui que entra em cena o presidente democrata (e Pr\u00eamio Nobel da Paz) Barack Obama, o qual em agosto de 2010 anuncia o ini\u0301cio da retirada das tropas, e dos aliados norte-americanos do Iraque, e o nascimento de uma \u00abnova alvorada\u00bb. Alvorada vermelha de sangue na realidade, que assinala a passagem da guerra aberta para a secreta, que os Estados Unidos estendem para a Si\u0301ria fronteiric\u0327a com o Iraque. Neste quadro surge o Estado isla\u0302mico no Iraque e no Levante (EIIL), o qual, declarando-se totalmente inimigo jurado dos Estados Unidos, e\u0301 de facto a pec\u0327a funcional da sua estrate\u0301gia. Na\u0303o foi por acaso que o EIIL arregimentou o grosso de suas forc\u0327as justamente na Si\u0301ria, onde um grande nu\u0301mero dos seus li\u0301deres e militantes apareceram depois de terem feito parte das formac\u0327o\u0303es isla\u0302micas li\u0301bias que, primeiro classificadas como terroristas, foram armadas, treinadas e financiadas pelos servic\u0327os secretos norte-americano para derrubar Muammar el-Qaddafi. Tendo-se juntado com militantes maioritariamente na\u0303o Si\u0301rios\u2014 vindos do Afeganista\u0303o, da Bo\u0301snia, da Cheche\u0301nia e de outros pai\u0301ses\u2014 eles foram abastecidos com armas por uma rede organizada pela CIA, e infiltrados na Si\u0301ria, sobretudo a atrave\u0301s da Turquia, para derrubar o presidente Bashar al-Assad.<\/p>\n<p>Dai o EIIL comec\u0327ou o seu avanc\u0327o no Iraque, atacando em particular as populac\u0327o\u0303es crista\u0303s. Ele forneceu assim a Washington, ate\u0301 ai\u0301 assistindo, oficialmente, como espectador exprimindo a propo\u0301sito mais ou menos \u00ab fortes preocupac\u0327o\u0303es\u00bb, a possibilidade de iniciar a terceira guerra do Iraque (mesmo se Obama, obviamente, na\u0303o a define como tal). Como ele declarou, em maio, os Estados Unidos utilizam a forc\u0327a militar em dois cena\u0301rios: quando os seus cidada\u0303os ou interesses sa\u0303o ameac\u0327ados; quando ocorre quando uma \u00abcrise humanita\u0301ria\u00bb de tais proporc\u0327o\u0303es que lhes e\u0301 impossi\u0301vel ficar a assistir sem fazer nada.<\/p>\n<p>Depois de ter provocado, em mais de vinte anos de guerra e de embargo, a morte de milho\u0303es de civis iraquianos, os Estados Unidos apresentam-se, agora, aos olhos do mundo como os salvadores do povo iraquiano. Trata-se \u2014precisou Barack Obama\u2014 de \u00abum projeto a longo prazo\u00bb. Para a nova ofensiva ae\u0301rea no Iraque, o CentCom (cuja \u00aba\u0301rea de responsabilidade\u00bb e\u0301 o Pro\u0301ximo-Oriente) conta ja\u0301 com 100 avio\u0303es e oito navios de guerra, mas pode usar muitas outras forc\u0327as, nomeadamente os 10 mil soldados americanos estacionados no Koweit e 2.000 fuzileiros navais a bordo.<\/p>\n<p>Os Estados Unidos relanc\u0327am assim a sua estrate\u0301gia para o controlo do Iraque, compreendendo a mesma o bloqueio a\u0300 China, que estabeleceu fortes lac\u0327os com Bagdade, via primeiro-ministro iraquiano Nouri al-Maliki, para incrementar a sua presenc\u0327a econo\u0301mica no pai\u0301s. Neste contexto, Washington tem todo o interesse na partic\u0327a\u0303o, de facto, do pai\u0301s em tre\u0302s Estados \u2013Curdo, Sunita e Xiita- mais facilmente controla\u0301veis. Nesta linha, a ministro italiana das Relac\u0327o\u0303es Exteriores Federica Mogherini promete um \u00ab apoio, ai\u0301 incluindo apoio militar, ao governo curdo\u00bb, mas na\u0303o ao governo central em Bagd\u00e1.<\/p>\n<p>http:\/\/www.voltairenet.org\/article185078.html<\/p>\n","protected":false},"excerpt":{"rendered":"\nManlio Dinucci\n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/6628\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[38],"tags":[],"class_list":["post-6628","post","type-post","status-publish","format-standard","hentry","category-c43-imperialismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-1IU","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=6628"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/6628\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=6628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=6628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=6628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}