{"id":8155,"date":"2015-05-06T15:14:38","date_gmt":"2015-05-06T18:14:38","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=8155"},"modified":"2015-05-12T06:04:39","modified_gmt":"2015-05-12T09:04:39","slug":"os-80-anos-da-alianca-nacional-libertadora","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/8155","title":{"rendered":"OS 80 ANOS DA ALIAN\u00c7A NACIONAL LIBERTADORA"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/grabois.org.br\/admin\/fotos\/foto_galeria_36_171.jpg?w=747\" alt=\"imagem\" \/>Frente pol\u00edtica de massas anti-imperialista, antilatifundi\u00e1ria e antifascista, a Alian\u00e7a Nacional Libertadora \u2013 ANL \u2013 foi oficialmente institu\u00edda no dia 30 de mar\u00e7o de 1935, em ato p\u00fablico realizado no Teatro Jo\u00e3o Caetano, no Rio de Janeiro. Agregou em torno de si <!--more-->personalidades, organiza\u00e7\u00f5es de trabalhadores, partidos e movimentos de corte revolucion\u00e1rio, democr\u00e1tico e progressista e sua constru\u00e7\u00e3o contou com a participa\u00e7\u00e3o ativa dos comunistas, tendo em Luiz Carlos Prestes, militante do PCB desde 1933, um de seus principais dirigentes, aclamado como presidente de honra.<\/p>\n<p>O programa popular revolucion\u00e1rio da ANL procurava contemplar reivindica\u00e7\u00f5es concretas das classes subalternas e extratos intermedi\u00e1rios da popula\u00e7\u00e3o brasileira, tais como: n\u00e3o reconhecimento e n\u00e3o pagamento da d\u00edvida externa; den\u00fancia dos tratados desiguais assinados com os pa\u00edses imperialistas; nacionaliza\u00e7\u00e3o dos servi\u00e7os p\u00fablicos essenciais e das empresas imperialistas que n\u00e3o se subordinassem ao poder revolucion\u00e1rio; jornada m\u00e1xima de oito horas; seguro social; aposentadorias; aumento de sal\u00e1rios; isonomia salarial e garantia de sal\u00e1rio m\u00ednimo; fim do trabalho escravo; elimina\u00e7\u00e3o dos latif\u00fandios; amplas liberdades democr\u00e1ticas; supress\u00e3o de quaisquer privil\u00e9gios de cor ou ra\u00e7a; total liberdade religiosa com a separa\u00e7\u00e3o entre Igreja e Estado; oposi\u00e7\u00e3o \u00e0s guerras imperialistas; estreitamento de rela\u00e7\u00f5es com as demais na\u00e7\u00f5es latino-americanas; solidariedade com todas as classes e povos oprimidos do mundo.<\/p>\n<p>O momento hist\u00f3rico em que se formou a ANL foi caracterizado por uma ampla ofensiva das for\u00e7as reacion\u00e1rias no Brasil e no mundo e pelo risco de guerras localizadas ou mesmo de uma conflagra\u00e7\u00e3o militar generalizada. Ap\u00f3s o refluxo das revolu\u00e7\u00f5es prolet\u00e1rias europeias que se seguiram ao Outubro russo de 1917 e ao t\u00e9rmino da Primeira Grande Guerra, inaugurou-se um ciclo de contrarrevolu\u00e7\u00f5es. A ascens\u00e3o do fascismo na It\u00e1lia e do nazismo na Alemanha e a capitula\u00e7\u00e3o das chamadas democracias liberais (Estados Unidos, Fran\u00e7a e Inglaterra) em face das aventuras praticadas pelos militaristas japoneses no Pac\u00edfico Oriental, pelo expansionismo hitleriano na Europa e pelo colonialismo italiano no norte da \u00c1frica ofereceram alento \u00e0s for\u00e7as da rea\u00e7\u00e3o internacional.<\/p>\n<p>No Brasil, a chamada A\u00e7\u00e3o Integralista Brasileira, fortemente influenciada por seus antecessores fascista e nazista, arregimentou expressivos contingentes com a finalidade de atuar como uma for\u00e7a de choque contrarrevolucion\u00e1ria em oposi\u00e7\u00e3o \u00e0 mobiliza\u00e7\u00e3o da classe oper\u00e1ria e das for\u00e7as populares. O pr\u00f3prio governo brasileiro \u2014 engajado desde o in\u00edcio da d\u00e9cada em um esfor\u00e7o de conter, enquadrar e desmobilizar o movimento dos trabalhadores \u2014 adotou leis e dispositivos jur\u00eddicos cerceadores das lutas de massas e aceitou de bom grado a ajuda prometida pelos integralistas. Foi neste esp\u00edrito que, em 5 de mar\u00e7o de 1935, durante o governo constitucional de Get\u00falio Vargas, entrou em vig\u00eancia a Lei de Seguran\u00e7a Nacional que promoveu as condi\u00e7\u00f5es necess\u00e1rias \u00e0 repress\u00e3o em larga escala do movimento aliancista, das lutas populares e do Partido Comunista. Em 5 de julho de 1935, quatro meses depois, Luiz Carlos Prestes divulgou um manifesto conclamando o povo e os trabalhadores a reagirem contra a amea\u00e7a integralista e o governo Vargas e a instaurar no pa\u00eds um poder popular nacional revolucion\u00e1rio.<\/p>\n<p>Em resposta, o governo central interditou a ANL e perseguiu seus militantes. Privados do \u00fanico instrumento de a\u00e7\u00e3o legal contra o que consideravam ser uma marcha em dire\u00e7\u00e3o \u00e0 fascistiza\u00e7\u00e3o do Brasil, dirigentes do PCB, militantes e l\u00edderes da ANL encabe\u00e7ados por Luiz Carlos Prestes\u2014 muitos deles veteranos das lutas tenentistas de 1922 e 1924 \u2014 se engajaram na prepara\u00e7\u00e3o de uma insurrei\u00e7\u00e3o armada.<\/p>\n<p>Entretanto, os acontecimentos se precipitaram. No Rio Grande do Norte, uma mobiliza\u00e7\u00e3o de trabalhadores contra o governo do estado resultou na destitui\u00e7\u00e3o do governador e na forma\u00e7\u00e3o de um governo nacional libertador. Impactada pelos acontecimentos na capital potiguar, a lideran\u00e7a clandestina da ANL desencadeou insurrei\u00e7\u00f5es militares em Recife e no Rio de Janeiro. Mal organizado e sem apoio popular, o movimento foi derrotado e, na esteira desta derrota, teve lugar um surto de repress\u00e3o contra os trabalhadores, os setores populares e a intelectualidade progressista, que culminou com a instaura\u00e7\u00e3o do Estado Novo, regime de forte influ\u00eancia fascista, a partir de 1937.<\/p>\n<p>Diferentemente do que tem sido repetidamente afirmado pelos setores reacion\u00e1rios da sociedade brasileira h\u00e1 quase oito d\u00e9cadas, a Alian\u00e7a Nacional Libertadora n\u00e3o organizou, sob as ordens de Moscou, um golpe comunista com a finalidade de sovietizar o pa\u00eds. Movimento pol\u00edtico plural, ela tinha objetivos nacionais e democr\u00e1ticos, anti-imperialistas e antilatifundi\u00e1rios. \u00c9 oportuno esclarecer que a iniciativa de cria\u00e7\u00e3o da ANL n\u00e3o partiu dos comunistas, sua presen\u00e7a e influ\u00eancia na entidade se adensaram gradativamente em propor\u00e7\u00e3o \u00e0 defini\u00e7\u00e3o dos objetivos da organiza\u00e7\u00e3o, ao aprofundamento dos embates com as for\u00e7as reacion\u00e1rias e ao recrudescimento da coer\u00e7\u00e3o governamental contra ela.<\/p>\n<p>Institu\u00edda em mar\u00e7o de 1935, sua concep\u00e7\u00e3o n\u00e3o resultou das decis\u00f5es do VII Congresso da Internacional Comunista, s\u00f3 conclu\u00eddo em agosto daquele mesmo ano. Pelo contr\u00e1rio, foram suas atividades e experi\u00eancias, assim como as coaliz\u00f5es antifascistas organizadas no mesmo per\u00edodo em Espanha e Fran\u00e7a que contribu\u00edram para a ado\u00e7\u00e3o pelo Kominter da Pol\u00edtica de Frentes Populares naquele congresso. Os levantes realizados em Natal, Recife e Rio de Janeiro n\u00e3o foram manifesta\u00e7\u00f5es de um <em>putschismo<\/em> revolucion\u00e1rio ou de um revolucionarismo golpista adotado formal e conscientemente pelo PCB, mas sim uma resposta precipitada e equivocada, apesar de heroica, ao avan\u00e7o do integralismo e \u00e0s inclina\u00e7\u00f5es autorit\u00e1rias do governo de Vargas dada pela ala radical do tenentismo, abrigada no seio das dire\u00e7\u00f5es da ANL e do PCB.<\/p>\n<p>Apesar de sua derrota e de seus erros, a ANL nos legou um exemplo de dedica\u00e7\u00e3o \u00e0s causas dos trabalhadores e do povo, demonstrando com sua experi\u00eancia que o caminho para a derrota das for\u00e7as da rea\u00e7\u00e3o e do imperialismo passa pela organiza\u00e7\u00e3o, mobiliza\u00e7\u00e3o e unifica\u00e7\u00e3o da classe oper\u00e1ria e seus aliados, dos setores progressistas e revolucion\u00e1rios, avan\u00e7ados e antifascistas.<\/p>\n<p><i>(Muniz Ferreira \u00e9 historiador e membro do Comit\u00ea Central do PCB) <\/i><\/p>\n","protected":false},"excerpt":{"rendered":"Frente pol\u00edtica de massas anti-imperialista, antilatifundi\u00e1ria e antifascista, a Alian\u00e7a Nacional Libertadora \u2013 ANL \u2013 foi oficialmente institu\u00edda no dia 30 de mar\u00e7o \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/8155\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"class_list":["post-8155","post","type-post","status-publish","format-standard","hentry","category-c56-memoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p659gw-27x","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/8155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=8155"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/8155\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=8155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=8155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=8155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}