{"id":8765,"date":"2015-07-02T12:59:51","date_gmt":"2015-07-02T15:59:51","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=8765"},"modified":"2015-07-20T14:41:44","modified_gmt":"2015-07-20T17:41:44","slug":"grecia-entrevista-de-kostas-papadakis-a-oddiario-info","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/8765","title":{"rendered":"Gr\u00e9cia: entrevista de Kostas Papadakis* a ODdiario.info"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.aporrea.org\/imagenes\/2012\/04\/protestas_en_grecia.jpg?w=747\" alt=\"imagem\" \/><b>Como avalia os resultados das negocia\u00e7\u00f5es do governo grego com a Comiss\u00e3o Europeia?<\/b><\/p>\n<p>O governo do Syriza-ANEL est\u00e1 h\u00e1 quatro meses em negocia\u00e7\u00e3o com a troika, as \u201cinstitui\u00e7\u00f5es\u201d, ou seja, a Comiss\u00e3o Europeia, o Banco Central Europeu (BCE) e o FMI, <!--more-->mas n\u00e3o a favor dos interesses do povo. Trata-se de uma negocia\u00e7\u00e3o com os credores, que \u00e9 <em>a priori<\/em>antipopular, com a qual o governo trata de assegurar os interesses da burguesia grega no quadro do antagonismo geral que se desenvolve entre os Estados Unidos e a Alemanha, assim como entre os pa\u00edses da zona do euro, sobre a f\u00f3rmula da gest\u00e3o capitalista. Essa negocia\u00e7\u00e3o reflete a confronta\u00e7\u00e3o geral em que a burguesia grega tem como objetivo, entre outros, assegurar um <em>superavit<\/em>baixo para os pr\u00f3ximos anos, passando capitais destinados \u00e0 amortiza\u00e7\u00e3o de empr\u00e9stimos para o financiamento estatal dos grupos empresariais. Com esses capitais como ferramenta, tentam se recuperar da crise capitalista. Portanto, os grupos empresariais e as associa\u00e7\u00f5es (Federa\u00e7\u00e3o de Ind\u00fastrias etc.) apoiam o governo que se apressou a servir aos seus interesses. O acordo antipopular de 20 de fevereiro j\u00e1 previa que se mantivessem as leis antipopulares do memorando aprovadas pelo ND e pelo PASOK, enquanto se preparam novas medidas antipopulares no sistema tribut\u00e1rio, privatiza\u00e7\u00f5es, aboli\u00e7\u00e3o de direitos de seguran\u00e7a social etc. As negocia\u00e7\u00f5es est\u00e3o levando a um novo acordo-memorando, seja qual for o seu nome.<br \/>\nPortanto os interesses do povo grego n\u00e3o s\u00e3o servidos se alinharem por planos antipopulares, que ali\u00e1s implicam medidas antitrabalhistas b\u00e1rbaras; ao contr\u00e1rio, \u00e9 necess\u00e1rio lutar contra eles de modo combativo e sem passividade. O povo n\u00e3o \u00e9 respons\u00e1vel pela d\u00edvida da plutocracia; nem a criou nem tem de pag\u00e1-la. Contra a l\u00f3gica de uma renegocia\u00e7\u00e3o antipopular, cujo resultado o povo j\u00e1 pagou e est\u00e3o a cham\u00e1-lo para pagar de novo, o KKE pede ao povo que exija a aboli\u00e7\u00e3o das leis antipopulares e a recupera\u00e7\u00e3o das perdas dos anos anteriores, abrir caminho para o cancelamento unilateral da d\u00edvida e, ao mesmo tempo, sair da UE, com o povo no poder.<\/p>\n<p>Cada trabalhador deve pensar que o SYRIZA se tinha comprometido a romper com os memorandos, mas agora traz outro e mant\u00e9m vigentes todas as leis do memorando. O KKE, ao contr\u00e1rio, apresentou de novo, em fevereiro, no Parlamento um projeto de lei para o cancelamento dos memorandos e das leis antipopulares pertinentes. Al\u00e9m disso, apresentou uma proposta para o restabelecimento do 13\u00ba sal\u00e1rio e do 14.o, aplica\u00e7\u00e3o imediata do sal\u00e1rio m\u00ednimo de 751\u20ac como base para aumentos \u2014 que haviam sido abolidos pelo governo da ND e do PASOK \u2014 aplica\u00e7\u00e3o obrigat\u00f3ria dos conv\u00eanios coletivos setoriais etc.<\/p>\n<p><strong>Como est\u00e3o reagindo os que votaram com o SYRIZA sobre os retrocessos perante as exig\u00eancias da Comiss\u00e3o Europeia que invalidam as promessas feitas durante e per\u00edodo eleitoral? E a classe oper\u00e1ria?<\/strong><\/p>\n<p>As \u201cpromessas\u201d eleitorais do SYRIZA, o chamado programa de Tessal\u00f3nica, eram migalhas que de qualquer modo n\u00e3o tirariam as fam\u00edlias da pobreza e da mis\u00e9ria. Tratava-se de medidas que reciclariam a pobreza mais extrema, mesmo sob a palavra de ordem: \u201ccontra a crise humanit\u00e1ria\u201d, exonerando o pr\u00f3prio sistema capitalista, dando a entender que se trata de uma ocasi\u00e3o excepcional e n\u00e3o da pr\u00f3pria natureza de um sistema explorador que est\u00e1 apodrecendo. Constituiriam mesmo os primeiros projetos de lei do governo que iam ser aprovados independentemente do resultado da negocia\u00e7\u00e3o. Mas logo depois das elei\u00e7\u00f5es, \u201co programa de Tessal\u00f3nica\u201d transformou-se de um programa de 100 dias num programa de quatro anos. Assim, as promessas de restabelecer o sal\u00e1rio m\u00ednimo passaram para um futuro long\u00ednquo e dependem do \u201capetite\u201d dos pr\u00f3prios empregadores. Enquanto o imposto sobre bens im\u00f3veis (ENFIA) mant\u00e9m-se no per\u00edodo pr\u00f3ximo. Assim, os impostos existentes est\u00e3o aumentando e o povo vai pagar muito caro o aumento das taxas de IVA. Ao mesmo tempo, o 13\u00ba m\u00eas (pelo Natal) foi adiado, mesmo para os mais fracos economicamente.<\/p>\n<p>O aumento do limite de entradas isentas de tributa\u00e7\u00e3o foi tamb\u00e9m adiado para os finais de 2016. Em contrapartida, est\u00e3o promovendo as privatiza\u00e7\u00f5es de portos, aeroportos, bloquearam as reservas dispon\u00edveis dos munic\u00edpios, de organismos estatais e os fundos de seguran\u00e7a destinados a cobrir as necessidades populares b\u00e1sicas. Enquanto se est\u00e1 planificando o corte das pens\u00f5es antecipadas e entre elas as profiss\u00f5es pesadas e insalubres, das mulheres trabalhadoras com filhos menores de idade etc. Perante essa pol\u00edtica governamental profundamente antipopular, os trabalhadores e outros setores populares pobres que acreditaram nas esperan\u00e7as que fomentaram as for\u00e7as da nova social-democracia do SYRIZA, n\u00e3o devem ficar decepcionados, mas sim tirar as conclus\u00f5es pol\u00edticas necess\u00e1rias. Ou seja, que n\u00e3o existem \u201csolu\u00e7\u00f5es f\u00e1ceis favor\u00e1veis ao povo\u201d quando o povo concede a responsabilidade a um governo que opera no quadro da UE e na senda do desenvolvimento capitalista. Portanto, o povo \u00e9 soberano s\u00f3 quando possui os meios de produ\u00e7\u00e3o, livre da UE, e pode satisfazer as suas necessidades com uma planifica\u00e7\u00e3o cient\u00edfica central.<\/p>\n<p><strong>Como interpreta o enfraquecimento relativo da rea\u00e7\u00e3o popular nos \u00faltimos meses? Quais s\u00e3o as perspectivas para a luta de massas no futuro pr\u00f3ximo?<\/strong><\/p>\n<p>Para l\u00e1 da repress\u00e3o e das provoca\u00e7\u00f5es utilizadas pelos governos da ND e do PASOK nos anos da crise, um fator determinante que foi usado para enfraquecer o movimento oper\u00e1rio e impedir o desenvolvimento da sua uni\u00e3o e da sua orienta\u00e7\u00e3o de classe, foi que a classe burguesa e o seu pessoal proporcionaram a ideia de que outro governo de gest\u00e3o burguesa se encarregar\u00e1 de resolver os problemas populares e dos trabalhadores. A inten\u00e7\u00e3o de apresentar o governo com o SYRIZA no seu n\u00facleo como salvador do povo provocou uma conten\u00e7\u00e3o grave do movimento oper\u00e1rio. Fomentou a passividade e falsas ilus\u00f5es, do que resultou que exista mesmo agora um retrocesso na luta oper\u00e1ria e popular. Nos primeiros dias depois das elei\u00e7\u00f5es, o novo governo levou o povo a aplaudir ativamente os objetivos da burguesia nas negocia\u00e7\u00f5es antipopulares. Poucos meses depois, cada vez mais gente compartilha as advert\u00eancias do KKE sobre o car\u00e1ter e a miss\u00e3o deste governo. Uma s\u00e9rie de mobiliza\u00e7\u00f5es de trabalhadores n\u00e3o remunerados, grevistas, contratadores nos centros de trabalho s\u00e3o um fen\u00f4meno di\u00e1rio. A greve dos trabalhadores no setor da sa\u00fade, em 20 de maio, foi um passo importante porque a situa\u00e7\u00e3o nos hospitais estatais \u00e9 explosiva dado que nem sequer t\u00eam gaze e os pacientes n\u00e3o s\u00f3 pagam caro por tudo, como ainda trazem os medicamentos de casa, materiais etc. As mobiliza\u00e7\u00f5es que o PAME est\u00e1 organizando em 11 de junho, reclamando que n\u00e3o se aplique o novo acordo antipopular, podem significar uma mudan\u00e7a na for\u00e7a, na combatividade do movimento oper\u00e1rio, podem marcar um novo ponto de partida para o confronto da ofensiva do governo, da UE e do capital contra o povo, para a recupera\u00e7\u00e3o das perdas. A organiza\u00e7\u00e3o do seu contra-ataque para a cria\u00e7\u00e3o de uma alian\u00e7a popular forte contra os monop\u00f3lios e o capitalismo.<\/p>\n<p><strong> As diverg\u00eancias no movimento comunista internacional atualmente s\u00e3o \u00f3bvias. A que se atribuem? Qual \u00e9 a posi\u00e7\u00e3o do KKE?<\/strong><\/p>\n<p>Sim, efetivamente h\u00e1 desacordos e diverg\u00eancias em assuntos-chave de import\u00e2ncia estrat\u00e9gica. Mas o crucial \u00e9 determinar qual \u00e9 a base s\u00f3lida e os crit\u00e9rios para examin\u00e1-los. Os alicerces est\u00e3o na cosmovis\u00e3o marxista-leninista, nos princ\u00edpios da luta de classes, na estrat\u00e9gia revolucion\u00e1ria. S\u00f3 nessa base \u00e9 poss\u00edvel fortalecer o verdadeiro car\u00e1ter comunista dos partidos comunistas, conquistar a unidade da classe oper\u00e1ria e a sua alian\u00e7a com as demais camadas populares pobres, conseguir agrupar e preparar as for\u00e7as trabalhadoras e populares para o derrubamento da barb\u00e1rie capitalista, pelo socialismo-comunismo. De outro modo, os partidos comunistas ficam expostos ao efeito corrosivo das for\u00e7as burguesas e oportunistas, ao parlamentarismo, \u00e0 incorpora\u00e7\u00e3o na gest\u00e3o burguesa, \u00e0s alian\u00e7as sem princ\u00edpios, \u00e0 participa\u00e7\u00e3o em governos de gest\u00e3o burguesa sob o t\u00edtulo de \u201cesquerdas\u201d \u201cprogressistas\u201d, \u00e0 op\u00e7\u00e3o e \u00e0 aliena\u00e7\u00e3o por detr\u00e1s das uni\u00f5es imperialistas, a converg\u00eancia com for\u00e7as e forma\u00e7\u00f5es oportunistas, como o chamado Partido da Esquerda Europeia ou a sua express\u00e3o pol\u00edtica, GUE-NGL. A base de tudo isso \u00e9 a l\u00f3gica daninha de etapas entre o capitalismo e o socialismo. O etapismo, que historicamente n\u00e3o se confirmou em caso algum, est\u00e1 a\u00ed para embelezar o capitalismo, para criar ilus\u00f5es de que se pode humaniz\u00e1-lo atrav\u00e9s da gest\u00e3o burguesa, com a participa\u00e7\u00e3o dos partidos comunistas. Esse caminho levou \u00e0 muta\u00e7\u00e3o e dissolu\u00e7\u00e3o de partidos comunistas, por exemplo, na Fran\u00e7a, na It\u00e1lia, na Espanha etc. Essa percep\u00e7\u00e3o de \u201cetapas\u201d, que se baseia em elabora\u00e7\u00f5es obsoletas do movimento comunista internacional, acalma o derrubamento do poder capitalista, o pr\u00f3prio socialismo, e fragiliza a prepara\u00e7\u00e3o da classe trabalhadora e dos seus aliados para essa tarefa monumental. Na pergunta crucial \u201crevolu\u00e7\u00e3o ou transforma\u00e7\u00e3o\u201d, o etapismo opta pela transforma\u00e7\u00e3o. O KKE quer um debate aberto e essencial entre os partidos comunistas sem etiquetas e sem aforismos sobre assuntos-chave de import\u00e2ncia estrat\u00e9gica para que se elabore uma estrat\u00e9gia revolucion\u00e1ria contempor\u00e2nea. Cada partido \u00e9 respons\u00e1vel por responder e justificar a sua opini\u00e3o e postura.<\/p>\n<p><strong>Como o KKE encara a ofensiva atual do imperialismo em m\u00faltiplas frentes: Ucr\u00e2nia, Oriente M\u00e9dio, Am\u00e9rica Latina, China, R\u00fassia?<\/strong><\/p>\n<p>Os Estados Unidos, tal como a Uni\u00e3o Europeia, a NATO e os seus governos, est\u00e3o levando a cabo planos perigosos contra os povos. O fortalecimento da articula\u00e7\u00e3o da UE com a NATO, assim como as interven\u00e7\u00f5es imperialistas independentes da UE com a forma\u00e7\u00e3o de um euro-ex\u00e9rcito regular e o fortalecimento das for\u00e7as militares para executar guerras e miss\u00f5es imperialistas pelos interesses dos monop\u00f3lios, confirmam a agudiza\u00e7\u00e3o dos antagonismos pelo controle dos mercados, das fontes e das rotas de transporte de energia. A corrida armamentista com as bandeiras da NATO, os programas avan\u00e7ados de armamento dos chamados pa\u00edses emergentes como a China e a R\u00fassia e de pa\u00edses do Oriente M\u00e9dio, s\u00e3o reveladores e constituem um prel\u00fadio perigoso da forma e dos m\u00e9todos com que o sistema capitalista procura se recuperar da sua crise profunda. S\u00e3o pura hipocrisia as alian\u00e7as das pot\u00eancias que est\u00e3o \u201cdispostas\u201d a atuar contra os jihadistas, que foram apoiados pela NATO, Estados Unidos e a UE, os traficantes de pessoas nos pa\u00edses onde a UE e seus aliados entraram a ferro e fogo em interven\u00e7\u00f5es imperialistas causando enormes vagas de imigrantes.<\/p>\n<p>O governo grego, que subscreveu tudo isso, anunciou que vai criar uma nova base da NATO no Egeu para as necessidades da UE e da NATO e dos planos imperialistas e que disponibilizar\u00e1 for\u00e7as armadas e bases a servi\u00e7o da NATO. Subscreveu todos os comunicados militares da UE nas reuni\u00f5es e dos ministros de assuntos exteriores e de defesa da UE, enquanto fortalece as rela\u00e7\u00f5es pol\u00edticas, econ\u00f4micas e militares com Israel que ataca o povo palestino. \u00c9 esse o governo das \u00abesquerdas\u00bb do SYRZA-ANEL \u2013 e queremos sublinhar que as for\u00e7as que se apressaram a celebr\u00e1-lo ficaram irremediavelmente expostas.<br \/>\nOs povos devem intensificar a sua luta para frustrar os planos imperialistas, pelo que \u00e9 necess\u00e1rio estar em vigil\u00e2ncia militante. O KKE desempenha um papel essencial na luta contra a implica\u00e7\u00e3o da Gr\u00e9cia nos planos imperialistas, exige que regressem as for\u00e7as militares gregas das miss\u00f5es euro-atl\u00e2nticas ao estrangeiro, que sejam encerradas as bases dos Estados Unidos e da NATO. O KKE luta pelo afastamento da NATO e da UE, sendo o povo dono do seu destino.<\/p>\n<p><strong>Como v\u00ea a nova estrat\u00e9gia de Barack Obama sobre as rela\u00e7\u00f5es dos Estados Unidos com Cuba?<\/strong><\/p>\n<p>\u00c9 particularmente importante que a longa luta do povo cubano em condi\u00e7\u00f5es muito dif\u00edceis e a mobiliza\u00e7\u00e3o mundial de solidariedade contra o bloqueio inaceit\u00e1vel dos Estados Unidos tenham exercido press\u00e3o sobre o governo dos Estados Unidos para discutir o seu levantamento. O mesmo acontece com a UE com a chamada Posi\u00e7\u00e3o Comum e as san\u00e7\u00f5es que imp\u00f5e h\u00e1 anos contra Cuba. Essa press\u00e3o e esse movimento mundial de solidariedade que se tem desenvolvido impulsionaram a liberta\u00e7\u00e3o dos cinco patriotas cubanos.<\/p>\n<p>Mas, n\u00e3o h\u00e1 qualquer complac\u00eancia ou ilus\u00e3o j\u00e1 que o imperialismo n\u00e3o deixa de utilizar tanto o engodo quanto o chicote com o fim de incorporar e subjugar os povos sob a sua estrat\u00e9gia. Por isso, \u00e9 necess\u00e1rio que a solidariedade internacional revele os ajustes da t\u00e1tica do advers\u00e1rio para que n\u00e3o se apliquem os planos que o imperialismo internacional est\u00e1 preparando e que se implementem atrav\u00e9s de san\u00e7\u00f5es, chantagem e amea\u00e7as ou negocia\u00e7\u00f5es.<\/p>\n<p><strong>Qual a opini\u00e3o do KKE sobre o chamado \u201cSocialismo do s\u00e9culo 21\u201d e o papel dos intelectuais de esquerda da Am\u00e9rica Latina a esse respeito? Mesmo hoje em dia, consideram como modelo os chamados governos progressistas, de esquerda, da Am\u00e9rica Latina?<\/strong><\/p>\n<p>Ainda hoje os chamados governos progressistas, de esquerdas, da Am\u00e9rica Latina que constroem o \u201csocialismo do s\u00e9culo 21\u201d s\u00e3o considerados como modelo. Essa fabrica\u00e7\u00e3o ideol\u00f3gica op\u00f5e-se \u00e0 pr\u00f3pria experi\u00eancia popular daqueles pa\u00edses, que est\u00e3o experimentando a pol\u00edtica antipopular, a pobreza, a explora\u00e7\u00e3o enquanto os monop\u00f3lios est\u00e3o enriquecendo. A fabrica\u00e7\u00e3o ideol\u00f3gica do \u201csocialismo do s\u00e9culo 21\u201d re\u00fane as diversas correntes social-democratas e oportunistas, acad\u00eamicos latino-americanos que garantem que falam em nome do marxismo, mas distorcem-no, porque o \u201csocialismo do s\u00e9culo 21\u201d no seu conjunto caracteriza-se pela agressividade contra o marxismo-leninismo e o movimento comunista internacional, promovendo como solu\u00e7\u00e3o as reformas burguesas que n\u00e3o afetam o poder do capital. \u00c9 a express\u00e3o de certos setores da burguesia, sobretudo na Am\u00e9rica Latina, que aspiram a uma melhoria do financiamento estatal para a cria\u00e7\u00e3o de infraestruturas, m\u00e3o-de-obra especializada necess\u00e1ria para os monop\u00f3lios \u2013 que n\u00e3o est\u00e3o dispostos a financi\u00e1-los \u2013 a fim de aumentar a sua rentabilidade. Uma orienta\u00e7\u00e3o semelhante existiu tamb\u00e9m nas d\u00e9cadas anteriores nos pa\u00edses da Europa Ocidental. Trata-se das necessidades das classes burguesas desses pa\u00edses para refor\u00e7ar a sua posi\u00e7\u00e3o no antagonismo internacional. O \u201csocialismo do s\u00e9culo 21\u201d \u00e9 uma fonte de distor\u00e7\u00e3o do conceito do socialismo cient\u00edfico j\u00e1 que n\u00e3o afeta o poder burgu\u00eas. \u00c9 apenas uma f\u00f3rmula de gest\u00e3o do sistema capitalista \u00e0s expensas da classe oper\u00e1ria e das demais camadas populares de cada pa\u00eds.<\/p>\n<p><strong>Quais as raz\u00f5es &#8211; em contradi\u00e7\u00e3o com a posi\u00e7\u00e3o de Marx sobre a extin\u00e7\u00e3o gradual do Estado \u2013 para que o Estado, em vez de enfraquecer, estava continuamente a se agigantar (URSS, Cuba, China)?<\/strong><\/p>\n<p>O estudo da experi\u00eancia da constru\u00e7\u00e3o socialista \u00e9 o assunto de que o nosso partido se tem ocupado nos \u00faltimos 20 anos. Tiramos conclus\u00f5es sobre os princ\u00edpios da constru\u00e7\u00e3o do socialismo atrav\u00e9s de um estudo a fundo, de um debate coletivo sobretudo da experi\u00eancia da URSS, principalmente das decis\u00f5es tomadas no \u00e2mbito da economia. Hoje em dia, esse debate \u00e9 necess\u00e1rio para cada partido comunista. Porque, por exemplo, \u00e9 um problema e uma express\u00e3o da situa\u00e7\u00e3o dif\u00edcil do movimento comunista internacional o fato de que hoje em dia existem partidos comunistas que negam os princ\u00edpios, as leis cient\u00edficas da constru\u00e7\u00e3o socialista, o poder oper\u00e1rio, a socializa\u00e7\u00e3o dos meios de produ\u00e7\u00e3o, a planifica\u00e7\u00e3o e o controle oper\u00e1rio e popular.<br \/>\nO KKE defende a necessidade da revolu\u00e7\u00e3o socialista e os princ\u00edpios da nova sociedade e, desse ponto de vista, participa no debate que est\u00e1 em curso no movimento comunista. Nessa perspectiva, examinamos, por exemplo, os acontecimentos na China onde, segundo os dados, prevalecem as rela\u00e7\u00f5es capitalistas de produ\u00e7\u00e3o.<\/p>\n<p>Para chegar ao ponto de falar da extin\u00e7\u00e3o do Estado, uma pr\u00e9-condi\u00e7\u00e3o necess\u00e1ria \u00e9 o fortalecimento das rela\u00e7\u00f5es de produ\u00e7\u00e3o comunistas, n\u00e3o o seu enfraquecimento. A experi\u00eancia hist\u00f3rica da contrarrevolu\u00e7\u00e3o, que ainda n\u00e3o acabou, mostra que a tarefa de desenvolver rela\u00e7\u00f5es comunistas de produ\u00e7\u00e3o e distribui\u00e7\u00e3o requer o desenvolvimento da teoria do comunismo cient\u00edfico pelo partido comunista atrav\u00e9s do estudo das leis da constru\u00e7\u00e3o socialista. A experi\u00eancia mostrou que os partidos no poder, na URSS e noutros Estados socialistas, n\u00e3o s\u00f3 n\u00e3o tiveram \u00eaxito nessa tarefa como tamb\u00e9m sofreram a eros\u00e3o do oportunismo e se transformaram em ve\u00edculos da contrarrevolu\u00e7\u00e3o e da restaura\u00e7\u00e3o do capitalismo.<\/p>\n<p><strong> O homem realizou conquistas destacadas no \u00e2mbito da ci\u00eancia e da t\u00e9cnica, mas mudou muito pouco desde a Gr\u00e9cia e Roma, como mostram as guerras, cada vez mais cru\u00e9is, e a escalada de crimes do imperialismo. A velocidade com que o \u201chomem velho\u201d reapareceu para milh\u00f5es na R\u00fassia e na China, e est\u00e1 a aparecer em Cuba, parece mostrar que a transi\u00e7\u00e3o do socialismo para o comunismo ser\u00e1 muito mais lenta do que o previsto por Marx e Engels. A hist\u00f3ria desmentiu o mito do \u201chomem novo\u201d? Que pensam disso?<\/strong><\/p>\n<p>N\u00e3o concordamos com essa ideia. Tudo o que afirmaram Marx e Engels, assim como L\u00eanin, se confirmou e confirma de modo absoluto hoje em dia. A resposta \u00e0 pergunta surge no pr\u00f3prio car\u00e1ter da \u00e9poca inaugurada pela Grande Revolu\u00e7\u00e3o Socialista, que \u00e9 a \u00e9poca da transi\u00e7\u00e3o do capitalismo para o socialismo. O capitalismo est\u00e1 na sua \u00faltima fase imperialista. As condi\u00e7\u00f5es materiais para a constru\u00e7\u00e3o do socialismo j\u00e1 est\u00e3o amadurecendo. O partido comunista deve, portanto, ser capaz de responder com a sua estrat\u00e9gia e t\u00e1tica para o desenvolvimento da luta de classes, ajudar a classe oper\u00e1ria a estar consciente da sua miss\u00e3o hist\u00f3rica, a prepar\u00e1-la para o confronto com o verdadeiro inimigo, ou seja a UE, os monop\u00f3lios e o seu poder. A elabora\u00e7\u00e3o da estrat\u00e9gia revolucion\u00e1ria \u00e9 a tarefa dos partidos comunistas independentemente da correla\u00e7\u00e3o de for\u00e7as.<\/p>\n<p>O objetivo \u00e9 que os partidos comunistas que cr\u00eaem na luta de classes e seus princ\u00edpios, na necessidade hist\u00f3rica do derrubamento do poder burgu\u00eas e na constru\u00e7\u00e3o do socialismo-comunismo elaborem uma estrat\u00e9gia que cumpra com a pr\u00f3pria raz\u00e3o da exist\u00eancia de um partido comunista: reunir for\u00e7as para o confronto com o poder dos monop\u00f3lios e n\u00e3o para a gest\u00e3o e perpetua\u00e7\u00e3o da barb\u00e1rie capitalista. O capitalismo \u00e9 um sistema apodrecido e obsoleto e nenhum modo de gest\u00e3o pode dar-lhe rosto humano. A luta pelo socialismo, portanto, n\u00e3o \u00e9 uma declara\u00e7\u00e3o para um futuro long\u00ednquo, mas um tema-chave que determina todos os outros. A quest\u00e3o-chave \u00e9 como um partido comunista trabalha dia ap\u00f3s dia para alcan\u00e7ar esse objetivo.<br \/>\n<em><br \/>\n* Membro do CC e eurodeputado do KKE<\/em><\/p>\n<p><em>Tradu\u00e7\u00e3o: Manuela Antunes<\/em><\/p>\n<p><a href=\"http:\/\/www.odiario.info\/?p=3692\">http:\/\/www.odiario.info\/?p=3692<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Como avalia os resultados das negocia\u00e7\u00f5es do governo grego com a Comiss\u00e3o Europeia? O governo do Syriza-ANEL est\u00e1 h\u00e1 quatro meses em negocia\u00e7\u00e3o \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/8765\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[107],"tags":[],"class_list":["post-8765","post","type-post","status-publish","format-standard","hentry","category-c120-grecia"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-2hn","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/8765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=8765"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/8765\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=8765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=8765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=8765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}