{"id":9037,"date":"2015-08-06T13:44:25","date_gmt":"2015-08-06T16:44:25","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=9037"},"modified":"2015-08-15T18:55:12","modified_gmt":"2015-08-15T21:55:12","slug":"70-anos-do-maior-atentado-terrorista-da-historia","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/9037","title":{"rendered":"70 ANOS DO MAIOR ATENTADO TERRORISTA DA HIST\u00d3RIA"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/images.hngn.com\/data\/images\/full\/97889\/mushroom-cloud.jpg?w=747\" alt=\"imagem\" \/>F\u00e1bio Bezerra*<\/p>\n<p>H\u00e1 exatos 70 anos, o mundo descobria o potencial destruidor de uma arma nuclear. No dia 06 de agosto de 1945 um avi\u00e3o cargueiro da for\u00e7a a\u00e9rea norte-americana lan\u00e7ava uma bomba at\u00f4mica sobre a cidade japonesa de Hiroshima exatamente as 8:15 da manh\u00e3 de uma segunda-feira. O impacto da bomba, chamada ironicamente pelos norte-americanos de \u201cLitlle Boy\u201d<!--more--> continha cerca de 50 quilos de ur\u00e2nio 235, com potencial de destrui\u00e7\u00e3o equivalente a 15 mil toneladas de TNT, o calor liberado pela bomba foi de 100 calorias\/cm\u00b2 no grau zero at\u00e9 cerca de 500 metros do epicentro da explos\u00e3o, que explodiu a cerca de 580 metros do solo e fez se elevar uma grande cortina de fuma\u00e7a que ficou conhecido como cogumelo at\u00f4mico a uma altura de 18 km.<\/p>\n<p>Hiroshima possu\u00eda em 1945 cerca de 250 mil habitantes. 40 mil pessoas morreram imediatamente a explos\u00e3o e cerca de 70 mil pessoas morreram em consequ\u00eancia da radia\u00e7\u00e3o logo nas primeiras semanas. Em 09 de agosto de 1945 uma segunda bomba nuclear, a fiss\u00e3o de plut\u00f4nio e de codinome: \u201cFast Man\u201d, explodiu sobre a cidade de Nagasaki. Estes dois ataques resultaram na morte de 200 mil pessoas apenas nas primeiras semanas ap\u00f3s os ataques.<\/p>\n<p>At\u00e9 os dias de hoje, segundo estimativas do governo japon\u00eas, 30 mil pessoas fazem tratamento de leucemia devido a decorr\u00eancia da radia\u00e7\u00e3o nuclear.<\/p>\n<p>O uso de armas at\u00f4micas no final da 2\u00aa grande guerra (1938- 1945) inaugurou no cen\u00e1rio mundial um novo cap\u00edtulo na hist\u00f3ria da humanidade. A era das armas de destrui\u00e7\u00e3o em massa e consecutivamente das amea\u00e7as e do poder b\u00e9lico das na\u00e7\u00f5es que as possuem.<\/p>\n<p>Essa nova etapa do processo de expans\u00e3o imperialista possibilitou diversos mecanismos pol\u00edticos que sustentavam &#8211; e ainda sustentam- a din\u00e2mica e os pretextos para a imposi\u00e7\u00e3o geopol\u00edtica dos interesses daqueles que det\u00e9m essa tecnologia.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"imagem\" src=\"https:\/\/lh6.googleusercontent.com\/phmhpLIN8ZGq5EekDqryK1qcAfVxG3ELLjeBq04FWug=w250-h215-no\" alt=\"imagem\" \/>Uma das din\u00e2micas foi a escalada sem precedentes do uso do desenvolvimento cient\u00edfico e consequentemente das novas tecnologias na \u00e1rea da f\u00edsica nuclear, para alimentar a ind\u00fastria armamentista nos anos 60, 70 e 80 e todo um discurso ideol\u00f3gico sustentado na l\u00f3gica da \u201cGuerra Fria\u201d que se justificou perante a opini\u00e3o p\u00fablica dos EUA e que mobilizou bilh\u00f5es de d\u00f3lares das reservas or\u00e7ament\u00e1rias, alimentando um dos setores mais expressivos pol\u00edtica e economicamente na economia norte-americana, o setor b\u00e9lico, que possui fortes liga\u00e7\u00f5es com o sistema financeiro.<\/p>\n<p>Todo o aparato b\u00e9lico, desde ent\u00e3o, tornou-se o epicentro nevr\u00e1lgico da pol\u00edtica externa estadunidense, alimentando as justificativas para os gastos militares e toda a malha industrial agregada a esse setor, o expansionismo imperialista em outras regi\u00f5es geograficamente estrat\u00e9gicas e as campanhas eleitorais ora dos republicanos ora de democratas que mantem estreitas rela\u00e7\u00f5es pol\u00edticas com esse setor.<\/p>\n<p>A conquista da tecnologia de armas at\u00f4micas, passou a ser prioridade para pa\u00edses que desejassem se impor no cen\u00e1rio mundial. Ao mesmo tempo, essa corrida armamentista influiu decisivamente no percurso da ci\u00eancia e da tecnologia ao longo do s\u00e9culo XX e no desenvolvimento de um novo conceito de racionalidade geopol\u00edtica e de novos instrumentos de press\u00e3o e controle pol\u00edtico e econ\u00f4mico.<\/p>\n<p>Um exemplo claro desse processo foi o ocorrido ap\u00f3s a crise dos m\u00edsseis em 1961, envolvendo diretamente as duas superpot\u00eancias nucleares ( EUA e a URSS) elevando a tens\u00e3o e a possibilidade de uma nova guerra mundial por cerca de 15 dias. Ap\u00f3s um acordo que envolveu diretamente Washigton e o Kremilin, a URSS retirou seus m\u00edsseis de Cuba ao passo que os EUA retirava, no mesmo per\u00edodo, seus m\u00edsseis da Turquia. A partir desse epis\u00f3dio uma s\u00e9rie de tratados foram sendo constru\u00eddos em diversas partes do mundo, influenciados sobretudo, pelas press\u00f5es da opini\u00e3o p\u00fablica endossada por grande parcela da comunidade cient\u00edfica, mas que teve a chancela e a opera\u00e7\u00e3o pol\u00edtica dos EUA em especial, de modo a controlar o desenvolvimento das pesquisas nucleares- principalmente na Am\u00e9rica Latina- restringindo o acesso a essas tecnologias ou condicionando a compra de equipamentos.<\/p>\n<p>Ap\u00f3s a assinatura do Tratado de n\u00e3o prolifera\u00e7\u00e3o de armas nucleares (TNP) em 1968, a Ag\u00eancia Internacional de Energia At\u00f4mica passou a fiscalizar as atividades cient\u00edficas no \u00e2mbito da tecnologia nuclear, o que tamb\u00e9m representou uma forma de controle, espionagem e inger\u00eancia em diversos momentos ao longo do s\u00e9culo. Recentemente o mundo presenciou esse tipo de manobra para justificar a opini\u00e3o p\u00fablica mundial, ataques ao Iraque, acusado de possuir armas qu\u00edmicas e material radioativo para ser usado contra dissidentes internos. Relat\u00f3rios da Ag\u00eancia insinuavam essas possibilidades.<\/p>\n<p>O resultado final, todos sabemos; cerca de 250 mil mortes com a ocupa\u00e7\u00e3o imperialista por mais de uma d\u00e9cada, a desnacionaliza\u00e7\u00e3o do petr\u00f3leo iraquiano atrav\u00e9s das grandes multinacionais do setor e o esfacelamento do pa\u00eds contribuindo com a instabilidade geopol\u00edtica local.<\/p>\n<p>Curiosamente, armas com material radioativo (ur\u00e2nio empobrecido) foram utilizados justamente pelos EUA na Guerra do Golfo e pela OTAN na guerra dos Balc\u00e3s ambos na d\u00e9cada de 90.<\/p>\n<p>Na d\u00e9cada de 50 do s\u00e9culo passado, a restri\u00e7\u00e3o e o controle do desenvolvimento tecnol\u00f3gico, sob o pretexto de se assegurar a \u201cpaz\u201d no continente, fez com que o professor Julius Oppernheimer, f\u00edsico estadunidense principal dirigente do Projeto Manhattan \u2013 projeto piloto, que em 1942 iniciou os trabalhos para a produ\u00e7\u00e3o da bomba at\u00f4mica- fizesse uma visita ao Brasil em 1953 e ap\u00f3s ter acesso aos projetos de desenvolvimento nuclear, retornou a seu pa\u00eds alertando as autoridades de que em breve o Brasil poderia criar uma bomba at\u00f4mica.<\/p>\n<p>Em 1978 o ent\u00e3o presidente dos EUA Jimmy Carter, diante das informa\u00e7\u00f5es dos servi\u00e7os de intelig\u00eancia veio pessoalmente ao Brasil pressionar o governo do Gal. Ernesto Geisel a desistir das pretens\u00f5es nucleares, principalmente ap\u00f3s a decis\u00e3o do governo em estabelecer um pacote de interc\u00e2mbio com a Alemanha que resultou na compra de Angra I e na transfer\u00eancia de tecnologia para o enriquecimento do ur\u00e2nio.<\/p>\n<p>No campo da ci\u00eancia e da tecnologia \u00e9 ineg\u00e1vel o questionamento \u00e9tico que se propalou pela comunidade cient\u00edfica em todo o mundo, sobre a instrumentaliza\u00e7\u00e3o da ci\u00eancia para fins de exterm\u00ednio em massa e o direito a pesquisas e desenvolvimento da tecnologia nuclear aos pa\u00edses chamados perif\u00e9ricos.<\/p>\n<p>Sobre a forma\u00e7\u00e3o de uma nova racionalidade geopol\u00edtica a quest\u00e3o da posse desse tipo de armamento passou a ter valor igual ou maior do que a influ\u00eancia econ\u00f4mica local ou mesmo a potencialidade das riquezas naturais.<\/p>\n<p>Mas tamb\u00e9m \u00e9 ineg\u00e1vel que todo o conjunto de esfor\u00e7os, por mais bem intencionados que sejam e com elevad\u00edssimo valor moral, em restringir e abolir as armas nucleares, n\u00e3o impediu a corrida armamentista mundo a fora e o exterm\u00ednio de milh\u00f5es de vidas humanas em guerras planejadas para sustentar n\u00e3o apenas a l\u00f3gica de dom\u00ednio imperialista, mas toda a complexa ind\u00fastria da guerra- a maior do mundo- que movimenta anualmente trilh\u00f5es de d\u00f3lares. As Guerras s\u00e3o sem sombra de d\u00favida, na l\u00f3gica do sistema capitalista, um lucrativo neg\u00f3cio!<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/-li3SeTzXKro\/VcPClUn-kTI\/AAAAAAAAKpg\/9w3RSMUH_Tw\/w250-h301-no\/rosa2.png?w=747&#038;ssl=1\" alt=\"imagem\" \/>Desde 1945, a ind\u00fastria armamentista intensificou em quantidade e qualidade destrutiva o seu arsenal. Armas qu\u00edmicas, biol\u00f3gicas, bacteriol\u00f3gicas, eletr\u00f4nicas e mais recentemente as nanotecnol\u00f3gicas, possuem um poder de destrui\u00e7\u00e3o capaz de aniquilar toda a humanidade e a biosfera. N\u00e3o raro, muitos desses artefatos s\u00e3o utilizados em escalas variadas nos mais variados conflitos, inclusive como forma de conten\u00e7\u00e3o e controle de levantes civis.<\/p>\n<p>Ironicamente, ou melhor, cinicamente, hoje os EUA se colocam na condi\u00e7\u00e3o de paladinos da seguran\u00e7a mundial sob o pretexto de coibir o acesso de grupos terroristas a material e tecnologia para a produ\u00e7\u00e3o das tem\u00edveis armas nucleares; por sua vez, o maior ato terrorista da hist\u00f3ria da humanidade, em todos os tempos, foram perpetrados pelos EUA h\u00e1 exatamente 70 anos, instaurando uma nova era de amea\u00e7as e inseguran\u00e7a que apesar do fim da chamada: \u201cGuerra Fria\u201d, ainda mant\u00e9m sob alerta a possibilidade de uso de armas at\u00f4micas como forma de assegurar o controle social e ou chantagear na\u00e7\u00f5es e povos que se rebelem contra a ordem do sistema.<\/p>\n<p>*F\u00e1bio Bezerra \u00e9 professor e membro do Comit\u00ea Central do PCB<\/p>\n","protected":false},"excerpt":{"rendered":"F\u00e1bio Bezerra* H\u00e1 exatos 70 anos, o mundo descobria o potencial destruidor de uma arma nuclear. No dia 06 de agosto de 1945 \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/9037\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[38],"tags":[],"class_list":["post-9037","post","type-post","status-publish","format-standard","hentry","category-c43-imperialismo"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-2lL","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=9037"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/9037\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=9037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}