{"id":9044,"date":"2015-08-06T21:54:46","date_gmt":"2015-08-07T00:54:46","guid":{"rendered":"http:\/\/pcb.org.br\/portal2\/?p=9044"},"modified":"2015-08-15T18:54:40","modified_gmt":"2015-08-15T21:54:40","slug":"a-crise-grega-o-desastre-da-esquerda-radical-e-as-carpideiras-neoreformistas-no-brasil","status":"publish","type":"post","link":"https:\/\/pcb.org.br\/portal2\/9044","title":{"rendered":"A crise grega, o desastre da \u201cesquerda radical\u201d e as carpideiras neoreformistas no Brasil"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"imagem\" title=\"imagem\" src=\"https:\/\/i0.wp.com\/www.diarioliberdade.org\/archivos\/imagenes\/articulos\/0910b\/290910_edmilson_empregos-30-08primeiro-g.jpg?w=747\" alt=\"imagem\" \/>Edmilson Costa*<\/p>\n<p>As crises t\u00eam um significado profundamente pedag\u00f3gico para as sociedades. Quanto maior a crise, mais se aproxima o momento da verdade para todos: Estado, governos, institui\u00e7\u00f5es p\u00fablicas e privadas, partidos pol\u00edticos, movimentos sociais. \u00c0 medida em que a crise se acirra, vai se fechando o espa\u00e7o para o oportunismo, a demagogia, as manipula\u00e7\u00f5es, as meias verdades, <!--more-->as falsas promessas, as solu\u00e7\u00f5es de compromissos, os pactos sociais. A crise n\u00e3o permite que ningu\u00e9m fique em cima do muro. Cada institui\u00e7\u00e3o ou lideran\u00e7a \u00e9 obrigada a se mostrar por inteiro, dizer com voz alta o que pensa, expor-se \u00e0 luz do sol sem prote\u00e7\u00e3o.<\/p>\n<p>As crises tamb\u00e9m s\u00e3o momentos em que chegam \u00e0 superf\u00edcie de maneira expl\u00edcita todas as contradi\u00e7\u00f5es da sociedade. As pessoas come\u00e7am a perceber claramente aquilo que antes estava ofuscado pela manipula\u00e7\u00e3o dos meios de comunica\u00e7\u00e3o e pela viseira ideol\u00f3gica repetida de maneira contumaz pelas classes dirigentes. Outro grande ensinamento das crises tamb\u00e9m \u00e9 o fato que nesses per\u00edodos os trabalhadores aprendem em dias de luta muito mais que em anos de calmaria, pois as manifesta\u00e7\u00f5es, as greves, as batalhas nos locais de trabalho, nos bairros, nos locais de estudo e lazer ensinam muito mais que o aprendizado formal que obtiveram ao longo da vida.<\/p>\n<p>Al\u00e9m disso, as crises representam os per\u00edodos mais tensos da luta de classes. Nesses per\u00edodos, os atores envolvidos no processo n\u00e3o podem agir como jogadores de p\u00f4quer: nestes momentos n\u00e3o h\u00e1 espa\u00e7o para blefes! Nesse sentido, a crise atual \u00e9 t\u00e3o grave, profunda e devastadora que n\u00e3o permite solu\u00e7\u00f5es de compromisso, como nos velhos tempos da social-democracia cl\u00e1ssica, quando o crescimento do capitalismo nos anos dourados keynesiano possibilitava algumas vantagens para os trabalhadores em troca da colabora\u00e7\u00e3o de classe e da paz social. Agora, essa rota de fuga foi cortada pela gravidade da crise. Com a crise e a desapari\u00e7\u00e3o da \u00e2ncora sovi\u00e9tica, o capitalismo voltou a seu estu\u00e1rio original de rudeza expl\u00edcita: explora\u00e7\u00e3o, mis\u00e9ria e pobreza.<\/p>\n<p>Essa \u00e9 a trag\u00e9dia do SYRIZA, a nova social-democracia fantasiada de \u201cesquerda radical\u201d. Esse partido, em fun\u00e7\u00e3o do seu car\u00e1ter de classe, dos seus objetivos estrat\u00e9gicos e de sua linha pol\u00edtica confusa e conciliat\u00f3ria, j\u00e1 entrou derrotado nessas negocia\u00e7\u00f5es. Isso porque acreditava, ao contr\u00e1rio do que vendia demagogicamente para as massas (fim dos memorandos, fim da austeridade, soberania nacional e resgate do emprego), num acordo com a <em>Troika<\/em> (Uni\u00e3o Europeia, Fundo Monet\u00e1rio Internacional e Banco Central Europeu), na v\u00e3 ilus\u00e3o de que seria poss\u00edvel conciliar os interesses dos trabalhadores com a Europa imperialista em crise aguda. Como j\u00e1 era esperado, mesmo com todas as concess\u00f5es humilhantes, n\u00e3o foram aceitos no clube do capital.<\/p>\n<p>Vale lembrar que o momento hist\u00f3rico em que a social-democracia pontificou entre os trabalhadores era outro e eles levaram cerca de um s\u00e9culo para se desmoralizar. Agora, com a crise, o tempo hist\u00f3rico para esta nov\u00edssima social-democracia eleitoreira se esgotou. N\u00e3o h\u00e1 espa\u00e7o nem para a social-democracia cl\u00e1ssica nem para a social-democracia retardat\u00e1ria. A crise \u00e9 tamanha que o capital n\u00e3o pode sequer ceder os an\u00e9is ou proporcionar as migalhas do passado. Para se ter uma ideia do n\u00edvel de desespero e degrada\u00e7\u00e3o do sistema capitalista, recentemente a chefa do FMI, Christine Lagarde, disse que os anci\u00e3os est\u00e3o vivendo muito e isso \u00e9 um risco para a economia global&#8230; Nessa situa\u00e7\u00e3o, como ceder \u00e0 m\u00e3o esquerda, se a m\u00e3o direita est\u00e1 vazia.<\/p>\n<p>Todas as organiza\u00e7\u00f5es que recentemente povoaram o imagin\u00e1rio dos ing\u00eanuos, dos movimentistas, autonomistas, ongueiros at\u00e9 os anticomunistas fantasiados de vermelho est\u00e3o destinadas a seguir o mesmo destino: o descr\u00e9dito junto \u00e0 popula\u00e7\u00e3o. \u00c9 o SYRIZA na Gr\u00e9cia, o Podemos na Espanha, Bloco de Esquerda em Portugal, o Partido da Esquerda Europeia, o Sinn Fein, na Irlanda, o Die Link, na Alemanha, o Todos, no Chile, e assim por diante. No Brasil, correntes e partidos reformistas se inspiram no Syriza como seu modelo pol\u00edtico. Com um discurso pretensamente de esquerda, passam aos trabalhadores a ilus\u00e3o de que \u00e9 poss\u00edvel \u201chumanizar\u201d o capitalismo sem romper com esse sistema. As carpideiras que hoje derramam l\u00e1grimas de crocodilho no Brasil e em v\u00e1rias partes do mundo diante da \u201ctrai\u00e7\u00e3o\u201d do SYRIZA deveriam acumular ainda mais l\u00e1grimas, pois esse ser\u00e1 o caminho dessas organiza\u00e7\u00f5es.<\/p>\n<p><strong>Balaio de caranguejo<\/strong><\/p>\n<p>Em verdade, o SYRIZA n\u00e3o \u00e9 nem nunca foi a \u201cesquerda radical\u201d, como os meios de comunica\u00e7\u00e3o costumam lhe chamar, nem a \u201cnova esquerda\u201d, como os movimentistas e autonomistas gostariam que fosse. O SYRIZA \u00e9 um partido essencialmente reformista, n\u00e3o se prop\u00f5e a sair da Uni\u00e3o Europeia, nem romper com o euro ou grande capital, quer apenas humanizar o capitalismo. Sua proje\u00e7\u00e3o foi insuflada pelos meios de comunica\u00e7\u00e3o, num excelente servi\u00e7o de rela\u00e7\u00f5es p\u00fablicas para desorientar os trabalhadores, isolar o verdadeiro inimigo do capital, o KKE (Partido Comunista Grego) e desmoralizar a esquerda perante as massas, como aconteceu no Brasil com o <em>Partido dos Trabalhadores<\/em>. Consciente ou inconscientemente o SYRIZA cumpriu esse papel, pois em pol\u00edtica n\u00e3o bastam as inten\u00e7\u00f5es: o que verdadeiramente interessa \u00e9 a pr\u00e1tica.<\/p>\n<p>Para um observador mais atento da conjuntura grega, \u00e9 importante assinalar que a pr\u00f3pria trajet\u00f3ria do SYRIZA e sua composi\u00e7\u00e3o social e ideol\u00f3gica n\u00e3o poderiam permitir um resultado diferente do que realmente aconteceu. Esta organiza\u00e7\u00e3o (Sinaspismos Rizospastikis Arister\u00e1s \u2013 sigla SYRYZA) inicialmente foi formada por dissidentes eurocomunistas do KKE; posteriormente a esse grupo inicial foram se juntando outras forma\u00e7\u00f5es, como ecologistas, mao\u00edsta, trotskistas, sociais-democratas, personalidades de esquerda e at\u00e9 dissidentes do PASOK, um verdadeiro balaio de caranguejos, cuja organiza\u00e7\u00e3o principal \u00e9 o Sinaspismos, \u00e0 qual pertence Alexis Tsipras<sup>1<\/sup>.<\/p>\n<p>Esses grupos todos se reuniram em maio de 2004 e fundaram o SYRIZA. Com a crise dos partidos tradicionais burgueses, o SYRIZA teve um crescimento mete\u00f3rico: em 2004, conseguiu apenas 3,3% dos votos para o Parlamento grego e seis das 300 cadeiras; em 2007, aumentou esse percentual para 5% e conseguiu e 14 cadeiras; a partir de 2012 a ascens\u00e3o foi vertiginosa, especialmente em fun\u00e7\u00e3o da crise, e tamb\u00e9m pelo fato de ser uma esquerda que se dizia \u201cradical\u201d, \u201crenovadora\u201d, diferente da esquerda tradicional, o KKE, e que iria acabar com austeridade e resgatar a soberania grega. Em fun\u00e7\u00e3o dessas singularidades, obteve uma repercuss\u00e3o extraordin\u00e1ria na m\u00eddia, inclusive nos principais meios de comunica\u00e7\u00e3o imperialistas. Em junho de 2012 o SYRIZA obteve 26,9% dos votos e 71 cadeiras. Estava aberto o caminho para se tornar o partido dirigente do governo grego: finalmente em 2015 o SYRIZA obteve 36,3% dos votos e 149 cadeiras no Parlamento, duas a menos que a maioria absoluta.<\/p>\n<p>A partir da vit\u00f3ria eleitoral Tsipras foi empossado como primeiro-ministro, mas o SYRIZA come\u00e7ou a tomar atitudes aparentemente estranhas. Surpreendentemente, optou por uma coliga\u00e7\u00e3o com um partido nacionalista de direita, Gregos Independentes, para compor a maioria parlamentar, quando poderia ter coligado com outras forma\u00e7\u00f5es de centro-esquerda no Parlamento. Para esse partido de direita entregou a pasta da Defesa. Como era come\u00e7o de governo, muitos torceram o nariz, mas absorveram a alian\u00e7a com um mal necess\u00e1rio, afinal a sociedade grega estaria envolvida agora numa batalha muito maior que era o fim da austeridade e o resgate da soberania nacional.<\/p>\n<p>Na verdade, essa alian\u00e7a era apenas o resultado de um processo que j\u00e1 vinha se desenvolvendo no interior do SYRIZA h\u00e1 algum tempo, onde os setores mais conciliadoras ganhavam espa\u00e7o \u00e0 medida em que o partido ampliava sua influ\u00eancia institucional. Seu programa foi se modificando, seus dirigentes buscavam se apresentar como pol\u00edticos respons\u00e1veis, que n\u00e3o tinham inten\u00e7\u00f5es de sair da zona do euro ou da Uni\u00e3o Europeia ou ainda tomar medidas unilaterais. O discurso internacional em rela\u00e7\u00e3o \u00e0s principais institui\u00e7\u00f5es imperialistas tamb\u00e9m foi se amoldando \u00e0 ordem: a odiada <em>Troika<\/em> passou a ser chamada de institui\u00e7\u00f5es, o memorando passou a ser denominado de acordo e os credores gregos obtiveram o grau de parceiros. N\u00e3o era s\u00f3 a forma que estava mudando velozmente. O SYRYZA n\u00e3o queria a luta, n\u00e3o queria preparar o povo para uma longa e dif\u00edcil batalha contra a oligarquia financeira, acreditava que era poss\u00edvel fazer omelete sem quebrar os ovos ou andar na chuva sem se molhar.<\/p>\n<p>Al\u00e9m disso, o SYRIZA tamb\u00e9m se transformou num partido de personalidades, onde a bancada parlamentar passou a substituir as bases partid\u00e1rias. No \u00faltimo Congresso, Tsipras foi eleito presidente pelo pr\u00f3prio Congresso, manobra que o transformou num ser intoc\u00e1vel, uma vez que s\u00f3 pode ser destitu\u00eddo cargo, mesmo cometendo os piores erros, por um outro congresso daqui a tr\u00eas anos. Dessa forma, o Comit\u00ea Central passou a ser um \u00f3rg\u00e3o sem qualquer poder de decis\u00e3o, pois n\u00e3o pode afastar nem mudar o presidente, a n\u00e3o ser que ele pr\u00f3prio concorde ou tamb\u00e9m aceite convocar um congresso extraordin\u00e1rio. Tsipras se transformou num reizinho jovem, que n\u00e3o deveria prestar contas para ningu\u00e9m. Isso se tornou uma absoluta verdade quando, \u00e0s v\u00e9speras do referendo, 109 dos 201 membros do Comit\u00ea Central assinaram um manifesto contra o acordo e mesmo assim sequer puderam se reunir ou barrar a decis\u00e3o j\u00e1 tomada por Tsipras.<\/p>\n<p><strong>Uma rendi\u00e7\u00e3o sem luta<\/strong><\/p>\n<p>\u00c9 importante enfatizar que a crise grega \u00e9 a s\u00edntese das contradi\u00e7\u00f5es do capitalismo e do reformismo nesse momento da hist\u00f3ria. Mas justi\u00e7a seja feita: a crise n\u00e3o come\u00e7ou com o SYRIZA, a crise \u00e9 do capital e foi aprofundada pelos governos conservadores precedentes, PASOK, Nova Democracia e outros. Mas a responsabilidade do SYRIZA est\u00e1 justamente em ter enganado o povo, ter realizado promessas que n\u00e3o iria cumprir, ter se rendido covardemente sem luta, rastejado humilhantemente perante a oligarquia financeira, mesmo quando 61,3% da popula\u00e7\u00e3o em referendo rejeitaram as medidas de austeridade, que agora cinicamente o SYRIZA tenta justificar como se fosse uma fatalidade. Realmente, o memorando acertado por Tsipras \u00e9 muito mais danoso ao povo grego que os memorandos anteriores e t\u00e3o humilhante que custa acreditar como um personagem que h\u00e1 pouco era festejado como estrela de primeira grandeza conseguiu se transformar t\u00e3o rapidamente num an\u00e3o pol\u00edtico.<\/p>\n<p>\u00c9 necess\u00e1rio conhecermos os pontos fundamentais do acordo para avaliarmos a profundidade do desastre e a incoer\u00eancia do reformismo. 1) Reforma da Previd\u00eancia: o governo se comprometeu a reformar a previd\u00eancia, com aumento da idade da aposentadoria para 67 anos e restri\u00e7\u00f5es \u00e0s chamadas aposentadorias precoces; 2) Reforma Trabalhista: revis\u00e3o dos acordos de negocia\u00e7\u00e3o coletiva, greves e demiss\u00f5es em geral e permiss\u00e3o para que o com\u00e9rcio possa abrir aos domingos; 3) Reforma Fiscal: o governo dever\u00e1 aumentar o Imposto Sobre Valor Agregado (IVA) relativo ao consumo, bem como a amplia\u00e7\u00e3o da base tribut\u00e1ria para aumento das receitas. 5) <em>Reforma da Administra\u00e7\u00e3o P\u00fablica<\/em>: redu\u00e7\u00e3o nos custos da administra\u00e7\u00e3o e corte autom\u00e1tico dos gastos para se adaptar \u00e0s metas do super\u00e1vit prim\u00e1rio. O Pa\u00eds ter\u00e1 ainda que reformar a justi\u00e7a civil, de forma a adequ\u00e1-la \u00e0s normas europeias e possibilitar o autoresgate dos bancos, preservar a independ\u00eancia do setor de estat\u00edstica e aprovar leis que tamb\u00e9m adaptem o sistema banc\u00e1rio ao restante da Europa.<\/p>\n<p>H\u00e1 ainda a maior das rendi\u00e7\u00f5es: a Gr\u00e9cia dever\u00e1 realizar uma privatiza\u00e7\u00e3o generalizada dos ativos p\u00fablicos, envolvendo os setores de energia el\u00e9trica, transporte, comunica\u00e7\u00f5es e at\u00e9 os pontos tur\u00edsticos como v\u00e1rias ilhas gregas. Esse fundo ter\u00e1 titularidade formal grega, mas ser\u00e1 supervisionado pela <em>Troika<\/em>, O resultado financeiro dessas privatiza\u00e7\u00f5es ser\u00e1 transferido para um <em>fundo de privatiza\u00e7\u00f5es<\/em>, com o qual os credores europeus esperam arrecadar 50 bilh\u00f5es de euros. Desse total, 75% ser\u00e3o destinados a pagamento da d\u00edvida externa e recapitaliza\u00e7\u00e3o dos bancos e apenas 25% poder\u00e3o ser alocados para investimento interno. Para se uma ideia da monstruosidade dessa medida, basta dizer que as privatiza\u00e7\u00f5es realizadas anteriormente pelos governos de direita somaram apenas cinco bilh\u00f5es de euros.<\/p>\n<p>Vale ressaltar que os credores, para humilhar ainda mais os l\u00edderes do SYRIZA, obrigaram a que o Parlamento grego aprovasse as medidas em tempo recorde (duas rodadas de aprova\u00e7\u00e3o j\u00e1 foram realizadas) e exigiram que todas as reformas fossem supervisionadas pela Troika, o que na pr\u00e1tica significa que o Pa\u00eds est\u00e1 sob a interven\u00e7\u00e3o da oligarquia financeira e se transformou numa esp\u00e9cie de protetorado dessas institui\u00e7\u00f5es. Tamb\u00e9m exigiram a sa\u00edda do governo do ministro das Finan\u00e7as, Yanis Varoufakis, que eles consideravam um negociador dif\u00edcil, o que tamb\u00e9m foi aceito por Tsipras; foi substitu\u00eddo por um outro ministro mais palat\u00e1vel. O n\u00edvel de humilha\u00e7\u00e3o foi tamanha que o pr\u00f3prio Varoufakis divulgou o que lhe foi dito por um dos personagens das negocia\u00e7\u00f5es: &#8220;Voc\u00ea pode at\u00e9 ter raz\u00e3o no que fala, mas n\u00f3s vamos esmag\u00e1-los&#8221;.<\/p>\n<p>Em outras palavras, o primeiro-ministro grego vergou a espinha, capitulou de maneira indigna, abandonou os compromissos com a popula\u00e7\u00e3o e se transformou num agente consciente da oligarquia financeira contra seu povo. Isso se tornou mais claro com a vota\u00e7\u00e3o no Parlamento: 229 a favor, 64 contra. Como 38 deputados do SYRIZA votaram contra ou se abstiveram (32 contra, seis absten\u00e7\u00f5es e ainda um deputado faltou \u00e0 vota\u00e7\u00e3o), a aprova\u00e7\u00e3o do memorando s\u00f3 foi poss\u00edvel porque os partidos de direita socorreram o SYRIZA na sua marcha para a desmoraliza\u00e7\u00e3o. Em outros termos, conflu\u00edram para os mesmos objetivos tanto a chamada \u201cesquerda radical\u201d quanto a direita que j\u00e1 tinha implementado os dois memorandos anteriores.<\/p>\n<p>Dois novos fatos pol\u00edticos vieram se juntar a essa conjuntura para compor o r\u00e1pido processo de degenera\u00e7\u00e3o do reformismo moderno. O primeiro foi a a\u00e7\u00e3o da pol\u00edcia, sob controle do governo do SYRIZA, que reprimiu brutalmente os manifestantes que protestavam em frente o Parlamento contra a aprova\u00e7\u00e3o do memorando, sem ficar nada a dever aos velhos tempos. O segundo \u00e9 a a\u00e7\u00e3o da lideran\u00e7a do SYRIZA: diante do fato de que alguns ministros e altos funcion\u00e1rios do governo votaram contra o memorando, resolveram fazer um expurgo generalizado, afastando do governo todos os ministros e funcion\u00e1rios que se manifestaram contra a capitula\u00e7\u00e3o. Essas duas medidas, de um lado, abrem espa\u00e7os para a implementa\u00e7\u00e3o de mais concess\u00f5es e medidas impopulares, bem como deixa o campo aberto para a repress\u00e3o generalizada que vir\u00e1 em fun\u00e7\u00e3o da indigna\u00e7\u00e3o da popula\u00e7\u00e3o, que est\u00e1 se sentindo frustrada e tra\u00edda.<\/p>\n<p>O custo social da rendi\u00e7\u00e3o<\/p>\n<p>Como enfatizamos anteriormente, a luta de classes n\u00e3o \u00e9 um jogo de p\u00f4quer: na luta de classes n\u00e3o tem blefe. Desde o in\u00edcio das negocia\u00e7\u00f5es, Tsipras e Varoufakis tinham a ilus\u00e3o de que seria poss\u00edvel alcan\u00e7ar uma negocia\u00e7\u00e3o vantajosa com o Eurogrupo, que era poss\u00edvel uma reforma da Uni\u00e3o Europeia a partir de dentro. Por isso, passaram a fazer um jogo duplo: enquanto acenavam com concess\u00f5es ao Eurogrupo e redefiniam os qualificativos para os credores, o memorando e a <em>Troika<\/em>, internamente faziam um discurso altivo contra a austeridade, em defesa da soberania nacional e dos trabalhadores, especialmente os mais pobres. O SYRIZA imaginava que o blefe e a bazofia seriam capazes de dobrar a oligarquia financeira. Vale ressaltar que as bravatas que falava internamente n\u00e3o tinha nenhuma base real: o SYRYZA nunca buscou organizar a popula\u00e7\u00e3o para a resist\u00eancia duradoura contra o Eurogrupo.<\/p>\n<p>Mesmo antes do desfecho das negocia\u00e7\u00f5es, Tsipras j\u00e1 tinha definido v\u00e1rias concess\u00f5es, dava mostra de que o seu discurso interno n\u00e3o era para valer e que n\u00e3o estava disposto ir \u00e0s \u00faltimas consequ\u00eancias caso os credores resolvessem endurecer. Isso se tornou mais claro especialmente a partir de uma carta que enviou aos negociadores aceitando v\u00e1rias medidas da receita de austeridade, al\u00e9m de entrevistas \u00e0 imprensa internacional no mesmo sentido. Parecia um bom menino querendo se mostrar bem comportado perante seus algozes. Dessa forma, quando os negociadores do grande capital perceberam a fragilidade do advers\u00e1rio desenvolveram um enredo n\u00e3o s\u00f3 para humilhar Tsipras e seu governo, mas especialmente para enviar uma mensagem a todos os povos esmagados pela d\u00edvida e pelas pol\u00edticas predat\u00f3rias de que este ser\u00e1 o tratamento dispensado a todos os rebeldes e que tamb\u00e9m ser\u00e1 in\u00fatil a rebeldia.<\/p>\n<p>Em outras palavras, a <em>Troika<\/em> utilizou a incoer\u00eancia e as ilus\u00f5es do reformismo para golpear profundamente a vontade de luta do povo grego, reduzir as perspectivas de uma rebeli\u00e3o popular e impor um severo retrocesso social, pol\u00edtico e econ\u00f4mico. Realmente, se levarmos em conta que o Pa\u00eds que j\u00e1 vinha sendo destro\u00e7ado pelas pol\u00edticas predat\u00f3rias da oligarquia financeira, o novo pacote de austeridade, se n\u00e3o houver resist\u00eancia popular, vai aprofundar a barb\u00e1rie. Afinal, o desemprego na Gr\u00e9cia est\u00e1 por volta de 28%, ressaltando-se que entre a popula\u00e7\u00e3o jovem esse \u00edndice atinge cerca de 60%, a renda m\u00e9dia caiu cerca de 40%<sup>2. Milhares de funcion\u00e1rios p\u00fablicos foram demitidos, as rela\u00e7\u00f5es trabalhistas desreguladas, as aposentadorias perderam cerca de 28% de seu poder de compra e mais de 40% das pessoas est\u00e3o vivendo abaixo da linha de pobreza. Numa situa\u00e7\u00e3o dessa ordem, aumentam os suic\u00eddios entre os aposentados. Um deles se enforcou e deixou um bilhete afirmando estar convicto de que um dia o povo grego vai reunir for\u00e7as suficientes para justi\u00e7ar em pra\u00e7a p\u00fablica todos os traidores do Pa\u00eds. Essa situa\u00e7\u00e3o, que j\u00e1 era dram\u00e1tica, vai se tornar ainda pior com as novas medidas aprovadas no Parlamento. O reformismo demonstrou n\u00e3o estar \u00e0 altura das tens\u00f5es da luta de classes nem \u00e0 altura da vontade do povo grego.<\/sup><\/p>\n<p>Todavia, o mais dram\u00e1tico \u00e9 que a rendi\u00e7\u00e3o aprovada pelo Parlamento grego n\u00e3o ir\u00e1 funcionar. Pelo contr\u00e1rio, a d\u00edvida grega, que era de 124% do PIB no in\u00edcio da crise j\u00e1 est\u00e1 por volta de 180% do PIB e crescer\u00e1 ainda mais e rapidamente, podendo chegar aos 200% at\u00e9 o final do ano. Isso significar\u00e1 mais imposi\u00e7\u00f5es para o pagamento de juros e novas medidas contra os trabalhadores e a popula\u00e7\u00e3o em geral. Com o aumento da recess\u00e3o que vir\u00e1, do desemprego, de mais empobrecimento das fam\u00edlias e tens\u00e3o social, haver\u00e1 queda nas receitas fiscais e depress\u00e3o profunda da economia. Como j\u00e1 foi demonstrado nos memorandos anteriores, essa receita predat\u00f3ria serve apenas para alimentar a vol\u00fapia da oligarquia financeira, aprofundar a crise e piorar as condi\u00e7\u00f5es de vida da popula\u00e7\u00e3o.<\/p>\n<p><strong>As carpideiras do social-reformismo<\/strong><\/p>\n<p>Mas esse drama nos leva a conclus\u00f5es importantes: a emerg\u00eancia do SYRIZA como organiza\u00e7\u00e3o pol\u00edtica da \u201cesquerda radical\u201d criou grandes ilus\u00f5es na esquerda internacional. Afinal, surgia no ber\u00e7o da democracia aquilo que era considerado aos quatro ventos como uma <em>esquerda renovada, n\u00e3o sect\u00e1ria, democr\u00e1tica<\/em>, que reunia os movimentos dos indignados com a globaliza\u00e7\u00e3o sem v\u00ednculo com o passado do socialismo real e, acima de tudo, disposta a enfrentar a Europa capitalista, a austeridade imposta pela Uni\u00e3o Europeia, Fundo Monet\u00e1rio Internacional e Banco Central Europeu e resgatar o orgulho grego. Era quase um milagre dos deuses a fazer surgir do Olimpo um Prometeu redentor capaz de resgatar a honra e a soberania da Gr\u00e9cia.<\/p>\n<p>Por isso mesmo ganhou a simpatia de grande parte da opini\u00e3o p\u00fablica progressista, de partidos pol\u00edticos, autonomistas, trotskistas e organiza\u00e7\u00f5es sociais em todos os continentes. Muitos intelectuais de peso internacional deram apoio \u00e0 nova organiza\u00e7\u00e3o. Delega\u00e7\u00f5es partid\u00e1rias visitavam a Gr\u00e9cia n\u00e3o s\u00f3 para reverenciar e apoiar a nova esquerda, mas principalmente para se credenciar como a vers\u00e3o do SYRIZA em seus pa\u00edses. Parecia que se tinha encontrado a pedra filosofal para a luta pol\u00edtica, principalmente porque parte do SYRIZA sa\u00edra das fileiras do Partido Comunista Grego (KKE), considerado por esse pessoal como stalinista, sect\u00e1rio e ultraesquerdista. Muita gente n\u00e3o levou em considera\u00e7\u00e3o desde o in\u00edcio as advert\u00eancias do KKE sobre essa esquerda renovada, seu car\u00e1ter de classe e plataforma pol\u00edtica. Estavam todos embriagados com a forma do fen\u00f4meno e sequer se deram ao trabalho de pesquisar as origens, observar a trajet\u00f3ria, seu programa e a pr\u00e1tica pol\u00edtica. Todas as cr\u00edticas vindas daqueles que estavam atuando teatro de opera\u00e7\u00f5es na Gr\u00e9cia era relegadas a um plano secund\u00e1rio.<\/p>\n<p>Quando nas elei\u00e7\u00f5es anteriores, o KKE se recusou a compor um governo com o SYRIZA e alertou sobre seu verdadeiro car\u00e1ter pol\u00edtico, recebeu cr\u00edticas violentas, grosseiras, muitas delas enfatizando o sectarismo e o ultraesquerdismo dos comunistas. Nas elei\u00e7\u00f5es de janeiro, quando o SYRIZA obteve condi\u00e7\u00f5es para formar o novo governo, essa esquerda parecia em \u00eaxtase. Notas de apoio e solidariedade foram enviadas por v\u00e1rias organiza\u00e7\u00f5es. Todo mundo queria estar pr\u00f3ximo ou se parecer com o SYRIZA. Ningu\u00e9m percebeu ou n\u00e3o quis perceber que o SYRIZA, em vez de chamar as for\u00e7as de centro-esquerda para compor o governo, pois necessitava de apenas dois deputados para compor a maioria absoluta, surpreendentemente comp\u00f4s com um partido nacionalista de direita (muitos comentam que este acordo j\u00e1 estava selado muito antes do resultado das elei\u00e7\u00f5es), mas isso era visto como uma flexibilidade t\u00e1tica, afinal para derrotar um inimigo maior era necess\u00e1rio certas concess\u00f5es internas.<\/p>\n<p>Ao longo de cinco meses Tsipras e Varoufakis negociaram com o Eurogrupo, sempre enfatizando que o objetivo das negocia\u00e7\u00f5es era acabar com austeridade, resgatar a soberania e desenvolver internamente um plano de salva\u00e7\u00e3o social. Quando as negocia\u00e7\u00f5es chegaram a um impasse e as ilus\u00f5es de que era poss\u00edvel um acordo com a oligarquia financeira se acabaram, ent\u00e3o Tsipras tentou uma \u00faltima cartada. Convocou um referendo para que a popula\u00e7\u00e3o se manifestasse contra ou a favor da austeridade. O KKE ainda tentou no Parlamento incluir no referendo um item no qual o povo deveria se manifestar tamb\u00e9m sobre o rompimento com os credores e a sa\u00edda do euro, mas essa proposta sequer foi posta em vota\u00e7\u00e3o no Parlamento. Isso j\u00e1 demonstrava que o SYRIZA n\u00e3o queria nem era capaz de enfrentar os credores europeus.<\/p>\n<p>Confiando nos discursos dos l\u00edderes do SYRIZA, a popula\u00e7\u00e3o votou em massa (61,3%) contra a austeridade. Surpreendentemente, ap\u00f3s o referendo, o l\u00edder do SYRIZA come\u00e7ou a mostrar sua verdadeira face: aceitou a press\u00e3o dos credores para a demiss\u00e3o de Varoufakis, enviou uma carta ao Eurogrupo na qual praticamente aceitava a maior parte das exig\u00eancias e deu entrevista \u00e0 imprensa internacional reafirmando os pontos em que estava disposto ceder. Percebendo o blefe do advers\u00e1rio, os negociadores do apertaram o torniquete e exigiram concess\u00f5es muito maiores do que aquilo que tinham oferecido anteriormente, sob pena da sa\u00edda da Gr\u00e9cia da zona do euro. Tsipras jogou a toalha e rastejou humilhantemente perante os negociadores.<\/p>\n<p>A partir da\u00ed mudou completamente o discurso e passou a defender abertamente as exig\u00eancias da <em>Troika<\/em>, com a mesma chantagem e os mesmos argumentos que partidos de direita fizeram anteriormente. O que veio depois todos j\u00e1 conhecem: aprova\u00e7\u00e3o das medidas de mais austeridade, repress\u00e3o aos trabalhadores que protestavam em frente ao Parlamente contra o memorando, expurgo dos ministros e funcion\u00e1rios do governo que se posicionaram ou votaram contra as medidas de austeridade e, agora, alian\u00e7a com os partidos de direita (PASOK, Nova Democracia, Potami), sem os quais n\u00e3o teria aprovado as medidas no Parlamento. Ou seja, as tens\u00f5es da luta de classes nesse momento de crise profunda do capitalismo s\u00e3o t\u00e3o grandes que a m\u00e1scara do reformismo levou somente seis meses para cair e, com sua queda, pode ter desmoralizado todas as experi\u00eancias semelhantes em gesta\u00e7\u00e3o pelo mundo.<\/p>\n<p>No Brasil, h\u00e1 uma prostra\u00e7\u00e3o generalizada. Praticamente, todos os agrupamentos de esquerda (\u00e0 exce\u00e7\u00e3o do PCB &#8211; Partido Comunista Brasileiro) embarcaram na onda do SYRIZA e agora, cabisbaixos e envergonhados, tentam justificar suas posi\u00e7\u00f5es e as pr\u00f3prias reviravoltas do SYRIZA. Outros passaram do apoio entusiasta \u00e0 cr\u00edtica aberta. Militantes do PT, para justificar a pol\u00edtica de seu governo e num del\u00edrio hist\u00f3rico, dizem que o que ocorreu na Gr\u00e9cia n\u00e3o foi a rendi\u00e7\u00e3o do SYRIZA, mas uma esp\u00e9cie de acordo de Brest-Litovski, no qual os bolcheviques foram obrigados a fazer concess\u00f5es para salvar a revolu\u00e7\u00e3o. Nas outras organiza\u00e7\u00f5es instala-se a prostra\u00e7\u00e3o generalizada, a tentativa envergonhada de justificar as medidas do SYRIZA como um mal menor, mas a verdade \u00e9 que a derrota pol\u00edtica do SYRIZA foi um banho de \u00e1gua fria no reformismo brasileiro. Outras correntes agora criticam o SYRIZA para salvar a pele, mas todos estavam entusiasmados e agora curtem a ressaca moral e pol\u00edtica.<\/p>\n<p>Em outros termos, est\u00e3o todos tontos, confusos, envergonhados, frustrados, chorando pelos cantos, mais perdidos que cego em tiroteio, procurando uma explica\u00e7\u00e3o para uma mudan\u00e7a t\u00e3o dr\u00e1stica de perspectivas. Afinal, o sonho de ser a vers\u00e3o nacional do reformismo grego se transformou num pesadelo. Dormiram no para\u00edso e acordaram pr\u00f3ximo ao inferno. E agora, sem refer\u00eancias internacionais, sem a \u00e2ncora que imaginavam redentora, o caminho se tornou bem mais dif\u00edcil. Mas \u00e9 importante assinalar que nenhuma dessas organiza\u00e7\u00f5es que se empolgaram com o SYRIZA teve a dignidade de fazer uma autocr\u00edtica das grosserias que assacaram contra o KKE antes do desfecho da trag\u00e9dia. O mais engra\u00e7ado \u00e9 que agora o KKE \u00e9 chamado de sect\u00e1rio, ultraesquerdista e coisas do g\u00eanero, quando em passado recente o acusavam de conter a luta dos trabalhadores. A coer\u00eancia n\u00e3o \u00e9 o forte desse pessoal.<\/p>\n<p>Existiria outra sa\u00edda al\u00e9m da rendi\u00e7\u00e3o?<\/p>\n<p>Estes acontecimentos que levaram a uma verdadeira trag\u00e9dia grega merecem uma reflex\u00e3o por parte de todas as for\u00e7as sociais e pol\u00edticas que desejam mudar o mundo e construir a nova sociedade. Mas antes, \u00e9 necess\u00e1rio responder \u00e0 quest\u00e3o central sobre a crise: existiria uma sa\u00edda para al\u00e9m da capitula\u00e7\u00e3o. Como se sabe n\u00e3o existe crise eterna nem crise sem sa\u00edda. E tamb\u00e9m na pol\u00edtica n\u00e3o existe v\u00e1cuo. Tsipras estava diante de uma disjuntiva: a rendi\u00e7\u00e3o ou a luta. Ele preferiu a primeira op\u00e7\u00e3o. Mas se a rendi\u00e7\u00e3o fosse a \u00fanica sa\u00edda para os povos explorados pelo imperialismo, o capitalismo seria um sistema eterno. Portanto, qualquer organiza\u00e7\u00e3o, seja militar ou pol\u00edtica, que capitula sem luta diante do inimigo n\u00e3o merece sequer existir. No caso grego, assim como em rela\u00e7\u00e3o aos pa\u00edses, a sa\u00edda n\u00e3o \u00e9 a rendi\u00e7\u00e3o, a sa\u00edda \u00e9 a luta.<\/p>\n<p>O fato \u00e9 que existia um leque de alternativas bem amplo. O ministro demission\u00e1rio Yanis Varoufakis prop\u00f4s criar um sistema paralelo de liquidez que poderia ser ativado em caso de asfixia financeira e que possibilitaria uma transi\u00e7\u00e3o para uma nova moeda. Tamb\u00e9m o ministro da Reconstru\u00e7\u00e3o Produtiva, da Energia e Meio Ambiente, Panayotis Lafazanis, da <em>Platafoma de Esquerda<\/em>, prop\u00f4s outra alternativa: o governo passaria a utilizar os 22 bilh\u00f5es de euros retidos Banco Central enquanto uma nova moeda n\u00e3o fosse introduzida. Para tanto, era necess\u00e1rio o governo intervir no Banco Central caso houvesse alguma resist\u00eancia, uma vez que seu presidente era ligado aos interesses da <em>Troika<\/em>. Evidentemente que essas duas solu\u00e7\u00f5es ainda n\u00e3o representavam o rompimento com o euro nem com a Uni\u00e3o Europeia e estavam ainda dentro da l\u00f3gica de resolver a crise grega sem romper com a <em>Troika<\/em>, mas pelo menos demonstravam alguma disposi\u00e7\u00e3o para a resist\u00eancia. Mas o novo reformismo n\u00e3o \u00e9 capaz de ser sequer uma caricatura da esquerda.<\/p>\n<p>Na verdade, a verdadeira sa\u00edda para a crise seria a luta que possibilitasse a mudan\u00e7a na correla\u00e7\u00e3o de for\u00e7as entre o povo grego e o imperialismo europeu. Essa luta envolveria o cancelamento unilateral da d\u00edvida grega, que \u00e9 a raiz principal dos problemas, a nacionaliza\u00e7\u00e3o dos bancos e dos grandes oligop\u00f3lios, o desligamento da Uni\u00e3o Europeia e do euro, al\u00e9m do fim das rela\u00e7\u00f5es com a OTAN, e um programa de mudan\u00e7as que inclu\u00edsse o resgate dos sal\u00e1rios dos trabalhadores e aposentados e a retomada da economia em novas bases, como um via de transi\u00e7\u00e3o para a reorganiza\u00e7\u00e3o da sociedade grega, baseada no interesse dos trabalhadores e da popula\u00e7\u00e3o em geral. Como ficou demonstrado, n\u00e3o existe a menor possibilidade de acordo com o imperialismo e muito menos \u00e9 poss\u00edvel reformar a Europa capitalista a partir de dentro, especialmente neste momento de crise sist\u00eamica global.<\/p>\n<p>Mas antes de tudo, era necess\u00e1rio um chamado ao povo grego em pra\u00e7a p\u00fablica em todas as regi\u00f5es do Pa\u00eds para tomar ci\u00eancia dos passos que o governo iria dar e das poss\u00edveis consequ\u00eancias do rompimento com o imperialismo europeu. Essas assembleias teriam um papel importante na prepara\u00e7\u00e3o da resist\u00eancia, a partir da organiza\u00e7\u00e3o nas f\u00e1bricas, nos estaleiros, nos bancos, nos bairros, nos escrit\u00f3rios, nas escolas e universidade e no campo para resistir a qualquer tipo de a\u00e7\u00e3o do inimigo. Mas isso \u00e9 pedir muito ao novo reformismo: ele n\u00e3o estava \u00e0 altura do povo grego.<\/p>\n<p>Uma sa\u00edda dessa magnitude com certeza criaria uma nova conjuntura internacional. Mesmo levando em conta que a Gr\u00e9cia representa apenas 2% do PIB europeu, a d\u00edvida externa est\u00e1 nas m\u00e3os principalmente dos bancos da Alemanha e da Fran\u00e7a e, portanto, um cancelamento da d\u00edvida impactaria todo o sistema financeiro europeu, em fun\u00e7\u00e3o dos fluxos de interdepend\u00eancia entre os bancos da regi\u00e3o e colocaria a crise no colo do imperialismo e n\u00e3o do povo grego. Al\u00e9m disso, seria um exemplo para os trabalhadores que est\u00e3o na mesma situa\u00e7\u00e3o na Espanha, em Portugal, na Irlanda, na It\u00e1lia e outros pa\u00edses, mudando assim as perspectivas da luta dos trabalhadores em toda a Europa.<\/p>\n<p>O SYRIZA, com o mandato popular da maioria da popula\u00e7\u00e3o, teve em suas m\u00e3os a possibilidade hist\u00f3rica de contribuir de maneira efetiva na luta contra o imperialismo, mas preferiu compor com o inimigo, com o argumento de que fora das regras impostas pelos algozes n\u00e3o haveria alternativas. No imagin\u00e1rio popular deve estar grassando uma grande frustra\u00e7\u00e3o, afinal todos imaginavam que o partido no governo respeitaria a vontade popular. Mas o custo pol\u00edtico dessa capitula\u00e7\u00e3o \u00e9 muito grande e ter\u00e1 repercuss\u00e3o tanto no interior do pr\u00f3prio SYRIZA quando nos outros partidos pol\u00edticos e na sociedade grega. Essa nova conjuntura dever\u00e1 impactar profundamente o quadro pol\u00edtico do Pa\u00eds e, independentemente do que venha a acontecer com o governo, haver\u00e1 uma reorganiza\u00e7\u00e3o das for\u00e7as pol\u00edticas tanto no interior do pr\u00f3prio SYRIZA, como nas outras for\u00e7as e organiza\u00e7\u00f5es sociais, pois numa conjuntura dessa ordem, a indigna\u00e7\u00e3o popular vai ser canalizada para algum tipo de a\u00e7\u00e3o pol\u00edtica.<\/p>\n<p>Como aconteceu com o Partido dos Trabalhadores no Brasil, uma parte da esquerda do SYRIZA vai continuar vociferando contra a dire\u00e7\u00e3o majorit\u00e1ria, mas aos poucos ir\u00e1 se adaptar at\u00e9 a integra\u00e7\u00e3o, muito embora de vez em quando queira se diferenciar da maioria. Outra parte poder\u00e1 romper com o SYRIZA e formar outra organiza\u00e7\u00e3o, como aconteceu com o PSOL no Brasil. O setor majorit\u00e1rio do SYRYZA, se continuar governando, tomar\u00e1 medidas cada vez mais \u00e0 direita e se integrar\u00e1 \u00e0 ordem, mesmo mantendo um discurso formalmente progressista, para continuar enganando os trabalhadores.<\/p>\n<p>Como a experi\u00eancia j\u00e1 demonstrou, \u00e9 melhor para o imperialismo que um partido dito de esquerda realize o trabalho sujo, pois os partidos tradicionais j\u00e1 est\u00e3o bastante desgastados junto \u00e0 popula\u00e7\u00e3o. Assim se torna mais f\u00e1cil para o capital atingir seus objetivos. O reformismo apresentar\u00e1 essas medidas como o mal menor, mas seguir\u00e1 em frente na sua saga de fazer o papel da m\u00e3o esquerda do imperialismo. Esse filme n\u00f3s j\u00e1 vimos no Brasil e muitas vezes quando alert\u00e1vamos os camaradas em f\u00f3runs internacionais ou em bilaterais \u00e9ramos vistos como sect\u00e1rios e esquerdistas. Agora a bola est\u00e1 novamente com o povo grego que, por sua tradi\u00e7\u00e3o de luta, saber\u00e1 encontrar os para dar a volta por cima e buscar sua emancipa\u00e7\u00e3o.<br \/>\n* Edmilson Costa \u00e9 Secret\u00e1rio de Rela\u00e7\u00f5es Internacionais do Comit\u00ea Central do Partido Comunista Brasileiro (PCB)<br \/>\n1. O SYRIZA \u00e9 formado por 12 organiza\u00e7\u00f5es, sendo o Sinaspismos, corrente de eurocomunistas expurgada do KKE com a crise da URSS, o bloco majorit\u00e1rio. As outras organiza\u00e7\u00f5es que formam o Syriza s\u00e3o as seguintes: AKOA (Esquerda Comunista, Ecol\u00f3gica e Renovadora); DEA (Esquerda Internacionalista dos Trabalhadores, trotskista); DKKI (Movimento Democr\u00e1tico e Social, que saiu do PASOK); KOE (Organiza\u00e7\u00e3o Comunista da Gr\u00e9cia, mao\u00edsta); KOKKINO (Vermelho, trotskistas); Cidad\u00e3os Ativos (Corrente fundada por Manolos Glezos, figura hist\u00f3rica grega e her\u00f3i da resist\u00eancia contra o nazismo); KEDA (Movimento pela Esquerda Unida na A\u00e7\u00e3o, cis\u00e3o do KKE em 2000); Rizospastes (cis\u00e3o dos Cidad\u00e3os Ativos \u2013 nacionalistas); Omada Roza (Grupo Roza, esquerda radical); APO (Grupo Pol\u00edtico Anticapitalista, ligada ao trotskismo). Al\u00e9m dessas organiza\u00e7\u00f5es, comp\u00f5em ainda o SYRYZA personalidades que v\u00e3o de sindicalistas a atletas ol\u00edmp\u00edcos.<\/p>\n<p>2. Os dados foram retirados de uma entrevista de Tsipras ao Le Monde, onde exp\u00f5e os dados que utilizamos e define as concess\u00f5es que estava disposto a fazer ao Eurogrupo<\/p>\n","protected":false},"excerpt":{"rendered":"Edmilson Costa* As crises t\u00eam um significado profundamente pedag\u00f3gico para as sociedades. Quanto maior a crise, mais se aproxima o momento da verdade \n<a class=\"moretag\" href=\"https:\/\/pcb.org.br\/portal2\/9044\"> <\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[107],"tags":[],"class_list":["post-9044","post","type-post","status-publish","format-standard","hentry","category-c120-grecia"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p659gw-2lS","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/9044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/comments?post=9044"}],"version-history":[{"count":0,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/posts\/9044\/revisions"}],"wp:attachment":[{"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/media?parent=9044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/categories?post=9044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcb.org.br\/portal2\/wp-json\/wp\/v2\/tags?post=9044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}